{"id":27761,"date":"2024-06-19T17:36:06","date_gmt":"2024-06-19T15:36:06","guid":{"rendered":"https:\/\/mamer.lu\/applications\/"},"modified":"2026-08-03T15:58:01","modified_gmt":"2026-08-03T13:58:01","slug":"applications","status":"publish","type":"page","link":"https:\/\/mamer.lu\/en\/procedures-2\/applications\/","title":{"rendered":"Online requests"},"content":{"rendered":"<p><\/p>\n<p><strong><style id=\"wpforms-css-vars-20875\">\n\t\t\t\t#wpforms-20875 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20875\"><form id=\"wpforms-form-20875\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20875\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761\" data-token=\"c8017c31da7e821568dc2c251f6621d6\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20875-field_59-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"59\"><fieldset><legend class=\"wpforms-field-label\">First and last name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20875-field_59\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][59][first]\" aria-errormessage=\"wpforms-20875-field_59-error\" aria-describedby=\"wpforms-20875-field_59-description\" required><label for=\"wpforms-20875-field_59\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20875-field_59-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][59][last]\" aria-errormessage=\"wpforms-20875-field_59-last-error\" aria-describedby=\"wpforms-20875-field_59-description\" required><label for=\"wpforms-20875-field_59-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><div id=\"wpforms-20875-field_59-description\" class=\"wpforms-field-description\">Indicate as marked on your identity document!<\/div><\/fieldset><\/div><div id=\"wpforms-20875-field_60-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"60\"><label class=\"wpforms-field-label\" for=\"wpforms-20875-field_60\">Date of birth <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-20875-field_60\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][60][date]\" aria-errormessage=\"wpforms-20875-field_60-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-20875-field_58-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"58\"><label class=\"wpforms-field-label\" for=\"wpforms-20875-field_58\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20875-field_58\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][58]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20875-field_58-error\" required><\/div><div id=\"wpforms-20875-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-20875-field_5\">Phone number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-20875-field_5\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Phone number\" aria-errormessage=\"wpforms-20875-field_5-error\" required><\/div><div id=\"wpforms-20875-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-20875-field_6\">Number and street <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20875-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-20875-field_6-error\" required><\/div><div id=\"wpforms-20875-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-20875-field_7\">Postal code <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20875-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-20875-field_7-error\" required><\/div><div id=\"wpforms-20875-field_24-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-20875-field_24\">Location<\/label><input type=\"text\" id=\"wpforms-20875-field_24\" class=\"wpforms-field-medium\" name=\"wpforms[fields][24]\" aria-errormessage=\"wpforms-20875-field_24-error\" ><\/div><div id=\"wpforms-20875-field_42-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"42\"><div id=\"wpforms-20875-field_42\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20875-field_42-error\"><h6><strong>CHOOSING THE POUCH TYPE&nbsp;<\/strong><\/h6>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20875-field_43-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"43\"><div id=\"wpforms-20875-field_43\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20875-field_43-error\"><h6><strong>Order black garbage can (residual waste)&nbsp;<\/strong><\/h6>\n<p><strong>Drain every 15 days<\/strong><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20875-field_44-container\" class=\"wpforms-field wpforms-field-html\" data-field-type=\"html\" data-field-id=\"44\"><div id=\"wpforms-20875-field_44\" aria-errormessage=\"wpforms-20875-field_44-error\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/jSibypQvgo4TUrE4J83xB6RpiXnczPq9HodOdffGE07YacLvFMf6l_pYn9fDpoyOra1p5dlgSZhxs2Ye0iFcDtShs0w74Nkjsy8BCqIcRl2HRB88AuW1SNt1Q5gmmQwT=w200\" alt=\"Price garbage can\" width=\"500\" height=\"600\"\/>\n<\/div><\/div><div id=\"wpforms-20875-field_45-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"45\"><fieldset><legend class=\"wpforms-field-label\">Black garbage can<\/legend><ul id=\"wpforms-20875-field_45\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_45_1\" name=\"wpforms[fields][45][]\" value=\"120 liters (\u20ac48.59\/piece)\" aria-errormessage=\"wpforms-20875-field_45_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_45_1\">120 liters (\u20ac48.59\/piece)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_45_2\" name=\"wpforms[fields][45][]\" value=\"240 liters (56.02\u20ac\/piece)\" aria-errormessage=\"wpforms-20875-field_45_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_45_2\">240 liters (56.02\u20ac\/piece)<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_45_3\" name=\"wpforms[fields][45][]\" value=\"660 liters (\u20ac217.15\/piece)\" aria-errormessage=\"wpforms-20875-field_45_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_45_3\">660 liters (\u20ac217.15\/piece)<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_45_4\" name=\"wpforms[fields][45][]\" value=\"1100 liters (316.31\/piece)\" aria-errormessage=\"wpforms-20875-field_45_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_45_4\">1100 liters (316.31\/piece)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-20875-field_46-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"46\"><div id=\"wpforms-20875-field_46\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20875-field_46-error\"><h6><strong>Order green garbage can (organic waste)&nbsp;<\/strong><\/h6>\n<p><strong>Drain according to season<\/strong><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20875-field_48-container\" class=\"wpforms-field wpforms-field-html\" data-field-type=\"html\" data-field-id=\"48\"><div id=\"wpforms-20875-field_48\" aria-errormessage=\"wpforms-20875-field_48-error\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/hdtwBGcrGV9sJjxwJEFxvgTaKXH6u0rTvgrYCnWCRGFo_wkzOIYxKknHj-h0jPaQlS058XYCTkpcBdQXJ3evaepQG4LrnRfadEnBVTbJNCpQv6ggqXYbiJbpG2JnEkmY=w200\" alt=\"Price garbage can\" width=\"500\" height=\"600\"\/>\n<\/div><\/div><div id=\"wpforms-20875-field_47-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"47\"><fieldset><legend class=\"wpforms-field-label\">Green garbage can<\/legend><ul id=\"wpforms-20875-field_47\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_47_1\" name=\"wpforms[fields][47][]\" value=\"120 liters (\u20ac48.59\/piece)\" aria-errormessage=\"wpforms-20875-field_47_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_47_1\">120 liters (\u20ac48.59\/piece)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_47_2\" name=\"wpforms[fields][47][]\" value=\"240 liters (56.02\u20ac\/piece)\" aria-errormessage=\"wpforms-20875-field_47_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_47_2\">240 liters (56.02\u20ac\/piece)<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_47_3\" name=\"wpforms[fields][47][]\" value=\"660 liters (\u20ac217.15\/piece)\" aria-errormessage=\"wpforms-20875-field_47_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_47_3\">660 liters (\u20ac217.15\/piece)<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_47_4\" name=\"wpforms[fields][47][]\" value=\"1100 liters (316.31\/piece)\" aria-errormessage=\"wpforms-20875-field_47_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_47_4\">1100 liters (316.31\/piece)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-20875-field_49-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"49\"><div id=\"wpforms-20875-field_49\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20875-field_49-error\"><h6><strong>Order blue garbage can (paper \/ cardboard)&nbsp;<\/strong><\/h6>\n<p><strong>Emptying once a month<\/strong><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20875-field_51-container\" class=\"wpforms-field wpforms-field-html\" data-field-type=\"html\" data-field-id=\"51\"><div id=\"wpforms-20875-field_51\" aria-errormessage=\"wpforms-20875-field_51-error\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/s0Jcn5ffsSjZKb0wd4P8WWHcJmuaBzahwvKbpb0mRlvskT7oima77YCKJzGGCnSZQ-CeIoNaAeN48PJo-GiGAppE8uf1b15ZRUJe0PPXEACGvGIHMeyt_Dc_raAioJX5=w200\" alt=\"Price garbage can\" width=\"500\" height=\"600\"\/>\n<\/div><\/div><div id=\"wpforms-20875-field_50-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"50\"><fieldset><legend class=\"wpforms-field-label\">Blue garbage can<\/legend><ul id=\"wpforms-20875-field_50\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_50_1\" name=\"wpforms[fields][50][]\" value=\"120 liters (\u20ac48.59\/piece)\" aria-errormessage=\"wpforms-20875-field_50_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_50_1\">120 liters (\u20ac48.59\/piece)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_50_2\" name=\"wpforms[fields][50][]\" value=\"240 liters (56.02\u20ac\/piece)\" aria-errormessage=\"wpforms-20875-field_50_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_50_2\">240 liters (56.02\u20ac\/piece)<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_50_3\" name=\"wpforms[fields][50][]\" value=\"660 liters (\u20ac217.15\/piece)\" aria-errormessage=\"wpforms-20875-field_50_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_50_3\">660 liters (\u20ac217.15\/piece)<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_50_4\" name=\"wpforms[fields][50][]\" value=\"1100 liters (316.31\/piece)\" aria-errormessage=\"wpforms-20875-field_50_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_50_4\">1100 liters (316.31\/piece)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-20875-field_52-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"52\"><div id=\"wpforms-20875-field_52\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20875-field_52-error\"><h6><strong>Yellow garbage can order (hollow glass)&nbsp;<\/strong><\/h6>\n<p><strong>Emptying once a month<\/strong><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20875-field_54-container\" class=\"wpforms-field wpforms-field-html\" data-field-type=\"html\" data-field-id=\"54\"><div id=\"wpforms-20875-field_54\" aria-errormessage=\"wpforms-20875-field_54-error\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/u_k6UG91cyVL4j00C-NPqLlc9ZhXkk3DxryYnfC6eAMxtOWUe7ZmC-IHdWHG_QI2ciaTsGuNTqCp8Im7SM618wMo_ozQZawk5xje1jJkRf-YcQCK9uuOIVdhDwl2tJNW=w200\" alt=\"Price garbage can\" width=\"500\" height=\"600\"\/>\n<\/div><\/div><div id=\"wpforms-20875-field_53-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"53\"><fieldset><legend class=\"wpforms-field-label\">Yellow garbage can<\/legend><ul id=\"wpforms-20875-field_53\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_53_1\" name=\"wpforms[fields][53][]\" value=\"120 liters (\u20ac48.59\/piece)\" aria-errormessage=\"wpforms-20875-field_53_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_53_1\">120 liters (\u20ac48.59\/piece)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_53_2\" name=\"wpforms[fields][53][]\" value=\"240 liters (56.02\u20ac\/piece)\" aria-errormessage=\"wpforms-20875-field_53_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_53_2\">240 liters (56.02\u20ac\/piece)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-20875-field_38-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"38\"><div id=\"wpforms-20875-field_38\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20875-field_38-error\"><h6><strong>Garbage can types and purchase prices (overview)<\/strong><\/h6>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20875-field_64-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"64\"><div id=\"wpforms-20875-field_64\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20875-field_64-error\"><p><img loading=\"lazy\" decoding=\"async\" height=\"182\" width=\"759\" alt=\"\" src=\"https:\/\/mamer.lu\/wp-content\/uploads\/2025\/02\/type-poubelleSITE-1.png\" class=\"alignnone wp-image-37271 size-full\" srcset=\"https:\/\/mamer.lu\/wp-content\/uploads\/2025\/02\/type-poubelleSITE-1.png 759w, https:\/\/mamer.lu\/wp-content\/uploads\/2025\/02\/type-poubelleSITE-1-480x115.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 759px, 100vw\" \/><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20875-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-20875-field_16\">Remarks<\/label><input type=\"text\" id=\"wpforms-20875-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-20875-field_16-error\" ><\/div><div id=\"wpforms-20875-field_56-container\" class=\"wpforms-field wpforms-field-radio sigi-field\" data-field-type=\"radio\" data-field-id=\"56\"><fieldset><legend class=\"wpforms-field-label\">I hereby declare that I wish to order one or more garbage cans at the price(s) indicated.\nAn invoice will be sent to you as soon as possible.   <\/legend><ul id=\"wpforms-20875-field_56\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-20875-field_56_1\" name=\"wpforms[fields][56]\" value=\"Send order\" aria-errormessage=\"wpforms-20875-field_56_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_56_1\">Send order<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-20875-field_17-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"17\"><label class=\"wpforms-field-label\">RGPD Agreement <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20875-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20875-field_17_1\" name=\"wpforms[fields][17][]\" value=\"I consent to this site storing my submitted information so that they may respond to my request.\" aria-errormessage=\"wpforms-20875-field_17_1-error\" aria-describedby=\"wpforms-20875-field_17-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20875-field_17_1\">I consent to this site storing my submitted information so that they may respond to my request.<\/label><\/li><\/ul><div id=\"wpforms-20875-field_17-description\" class=\"wpforms-field-description\">The data collected in this form is necessary for the processing of your file by the services of the Communal Administration, and if necessary by its subcontractors.\nIt is processed fairly and transparently in accordance with the General Data Protection Regulation (RGPD), and kept for the duration necessary for this processing as well as the applicable legal archiving period.\nIf you have any questions about the processing of personal data, you can contact the Data Protection Officer (DPO) at dpo@mamer.lu .  <\/div><\/div><div id=\"wpforms-20875-field_18-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-20875-field_18\">sigi-field<\/label><input type=\"text\" id=\"wpforms-20875-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" aria-errormessage=\"wpforms-20875-field_18-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20875\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20875\" class=\"wpforms-submit\" data-alt-text=\"Send...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/strong><\/p>\n<p><\/p>\n<p><strong><style id=\"wpforms-css-vars-20297\">\n\t\t\t\t#wpforms-20297 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20297\"><form id=\"wpforms-form-20297\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20297\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761\" data-token=\"ec7735565df1ffac27de2a8b910b0a01\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20297-field_13-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"13\"><fieldset><legend class=\"wpforms-field-label\">Pr\u00e9nom &amp; Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20297-field_13\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][13][first]\" aria-errormessage=\"wpforms-20297-field_13-error\" required><label for=\"wpforms-20297-field_13\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20297-field_13-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][13][last]\" aria-errormessage=\"wpforms-20297-field_13-last-error\" required><label for=\"wpforms-20297-field_13-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-20297-field_14-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-20297-field_14\">Date de naissance <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-20297-field_14\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][14][date]\" aria-errormessage=\"wpforms-20297-field_14-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-20297-field_15-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-20297-field_15\">Route et No <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20297-field_15\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][15]\" aria-errormessage=\"wpforms-20297-field_15-error\" required><\/div><div id=\"wpforms-20297-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-20297-field_16\">Localit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20297-field_16\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-20297-field_16-error\" required><\/div><div id=\"wpforms-20297-field_17-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-20297-field_17\">Code postal <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20297-field_17\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][17]\" aria-errormessage=\"wpforms-20297-field_17-error\" required><\/div><div id=\"wpforms-20297-field_10-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-20297-field_10\">Num\u00e9ro de t\u00e9l\u00e9phone portable <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-20297-field_10\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][10]\" value=\"+352\" aria-label=\"Num\u00e9ro de t\u00e9l\u00e9phone portable\" aria-errormessage=\"wpforms-20297-field_10-error\" required><\/div><div id=\"wpforms-20297-field_1-container\" class=\"wpforms-field wpforms-field-email sigi-media\" data-field-type=\"email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-20297-field_1\">E-Mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20297-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20297-field_1-error\" required><\/div><div id=\"wpforms-20297-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-20297-field_2\">Remarques<\/label><textarea id=\"wpforms-20297-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-20297-field_2-error\" ><\/textarea><\/div><div id=\"wpforms-20297-field_18-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"18\"><label class=\"wpforms-field-label\">Accord RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20297-field_18\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20297-field_18_1\" name=\"wpforms[fields][18][]\" value=\"Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.\" aria-errormessage=\"wpforms-20297-field_18_1-error\" aria-describedby=\"wpforms-20297-field_18-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20297-field_18_1\">Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.<\/label><\/li><\/ul><div id=\"wpforms-20297-field_18-description\" class=\"wpforms-field-description\">Les donn\u00e9es r\u00e9colt\u00e9es dans ce formulaire sont n\u00e9cessaires au traitement de votre dossier par les services de l\u2019Administration communale, et le cas \u00e9ch\u00e9ant par ses sous-traitants. Elles sont trait\u00e9es de mani\u00e8re loyale et transparente conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD), et conserv\u00e9es la dur\u00e9e n\u00e9cessaire \u00e0 ce traitement ainsi qu\u2019au d\u00e9lai d\u2019archivage l\u00e9gal applicable.\r\n\r\nEn cas de question au sujet du traitement des donn\u00e9es personnelles, vous pouvez contacter le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPD) \u00e0 l\u2019adresse dpo@mamer.lu .<\/div><\/div><div id=\"wpforms-20297-field_12-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-20297-field_12\">sigi-field<\/label><input type=\"text\" id=\"wpforms-20297-field_12\" class=\"wpforms-field-medium\" name=\"wpforms[fields][12]\" aria-errormessage=\"wpforms-20297-field_12-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20297\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20297\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/strong><\/p>\n<p><\/p>\n<p><span><style id=\"wpforms-css-vars-24662\">\n\t\t\t\t#wpforms-24662 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-24662\"><form id=\"wpforms-form-24662\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"24662\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761?wpforms_form_id=24662\" data-token=\"0e37bb472dbf5573786ebcb800031d09\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-24662-field_169-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"169\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24662-field_170-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"170\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_170\">First name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24662-field_170\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][170]\" aria-errormessage=\"wpforms-24662-field_170-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24662-field_171-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"171\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_171\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24662-field_171\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][171]\" aria-errormessage=\"wpforms-24662-field_171-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24662-field_163-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"163\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24662-field_164-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"164\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_164\">N\u00b0 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24662-field_164\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][164]\" aria-errormessage=\"wpforms-24662-field_164-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24662-field_165-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"165\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_165\">Rue <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24662-field_165\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][165]\" required=\"required\"><option value=\"rue Anne Beffort\"  selected='selected' class=\"choice-50 depth-1\"  >rue Anne Beffort<\/option><option value=\"route d&#039;Arlon\"  class=\"choice-8 depth-1\"  >route d'Arlon<\/option><option value=\"rue du Baerendall\"  class=\"choice-17 depth-1\"  >rue du Baerendall<\/option><option value=\"Domaine Beaulieu\"  class=\"choice-9 depth-1\"  >Domaine Beaulieu<\/option><option value=\"rue Josy Barthel\"  class=\"choice-37 depth-1\"  >rue Josy Barthel<\/option><option value=\"rue Pierre Krier-Becker\"  class=\"choice-29 depth-1\"  >rue Pierre Krier-Becker<\/option><option value=\"Bellevue Street\"  class=\"choice-10 depth-1\"  >Bellevue Street<\/option><option value=\"rue de Bertrange\"  class=\"choice-16 depth-1\"  >rue de Bertrange<\/option><option value=\"rue Op Bierg\"  class=\"choice-3 depth-1\"  >rue Op Bierg<\/option><option value=\"rue du Centre\"  class=\"choice-32 depth-1\"  >rue du Centre<\/option><option value=\"rue du Commerce\"  class=\"choice-33 depth-1\"  >rue du Commerce<\/option><option value=\"rue Jo Cox\"  class=\"choice-48 depth-1\"  >rue Jo Cox<\/option><option value=\"rue Cun\u00e9gonde\"  class=\"choice-19 depth-1\"  >rue Cun\u00e9gonde<\/option><option value=\"rue de Dang\u00e9-St-Romain\"  class=\"choice-4 depth-1\"  >rue de Dang\u00e9-St-Romain<\/option><option value=\"route de Dippach\"  class=\"choice-34 depth-1\"  >route de Dippach<\/option><option value=\"rue de l&#039;Ecole\"  class=\"choice-7 depth-1\"  >rue de l'Ecole<\/option><option value=\"rue Ermesinde\"  class=\"choice-22 depth-1\"  >rue Ermesinde<\/option><option value=\"rue Raoul Follereau\"  class=\"choice-30 depth-1\"  >rue Raoul Follereau<\/option><option value=\"rue Nicolas Frantz\"  class=\"choice-51 depth-1\"  >rue Nicolas Frantz<\/option><option value=\"rue Madeleine Frieden-Kinnen\"  class=\"choice-52 depth-1\"  >rue Madeleine Frieden-Kinnen<\/option><option value=\"rue Gaaschtbierg\"  class=\"choice-45 depth-1\"  >rue Gaaschtbierg<\/option><option value=\"rue Klengliller\"  class=\"choice-12 depth-1\"  >rue Klengliller<\/option><option value=\"Kitschenerwee\"  class=\"choice-2 depth-1\"  >Kitschenerwee<\/option><option value=\"rue Indira Gandhi\"  class=\"choice-11 depth-1\"  >rue Indira Gandhi<\/option><option value=\"rue de la Gare\"  class=\"choice-6 depth-1\"  >rue de la Gare<\/option><option value=\"Place de l&#039;Ind\u00e9pendance\"  class=\"choice-36 depth-1\"  >Place de l'Ind\u00e9pendance<\/option><option value=\"rue Elsy Jacobs\"  class=\"choice-53 depth-1\"  >rue Elsy Jacobs<\/option><option value=\"rue Henri Kirpach\"  class=\"choice-35 depth-1\"  >rue Henri Kirpach<\/option><option value=\"rue Kneppchen\"  class=\"choice-39 depth-1\"  >rue Kneppchen<\/option><option value=\"rue Karewee\"  class=\"choice-38 depth-1\"  >rue Karewee<\/option><option value=\"rue de Kehlen\"  class=\"choice-1 depth-1\"  >rue de Kehlen<\/option><option value=\"rue de la Lib\u00e9ration\"  class=\"choice-40 depth-1\"  >rue de la Lib\u00e9ration<\/option><option value=\"rue Anna Lindh\"  class=\"choice-13 depth-1\"  >rue Anna Lindh<\/option><option value=\"rue Mameranus\"  class=\"choice-46 depth-1\"  >rue Mameranus<\/option><option value=\"rue Marie-Paule Molitor-Peffer\"  class=\"choice-42 depth-1\"  >rue Marie-Paule Molitor-Peffer<\/option><option value=\"rue Mambra\"  class=\"choice-18 depth-1\"  >rue Mambra<\/option><option value=\"rue du March\u00e9\"  class=\"choice-41 depth-1\"  >rue du March\u00e9<\/option><option value=\"rue des Maximins\"  class=\"choice-27 depth-1\"  >rue des Maximins<\/option><option value=\"rue Golda Meir\"  class=\"choice-14 depth-1\"  >rue Golda Meir<\/option><option value=\"rue du Mill\u00e9naire\"  class=\"choice-28 depth-1\"  >rue du Mill\u00e9naire<\/option><option value=\"rue Simone Veil\"  class=\"choice-49 depth-1\"  >rue Simone Veil<\/option><option value=\"Margaret Thatcher Street\"  class=\"choice-15 depth-1\"  >Margaret Thatcher Street<\/option><option value=\"Roudewee\"  class=\"choice-24 depth-1\"  >Roudewee<\/option><option value=\"rue des Roses\"  class=\"choice-47 depth-1\"  >rue des Roses<\/option><option value=\"rue des Pr\u00e8s\"  class=\"choice-25 depth-1\"  >rue des Pr\u00e8s<\/option><option value=\"rue Sigefroi\"  class=\"choice-21 depth-1\"  >rue Sigefroi<\/option><option value=\"rue Fran\u00e7ois Trausch\"  class=\"choice-44 depth-1\"  >rue Fran\u00e7ois Trausch<\/option><option value=\"rue Yolande\"  class=\"choice-23 depth-1\"  >rue Yolande<\/option><option value=\"rue Wieseck\"  class=\"choice-31 depth-1\"  >rue Wieseck<\/option><option value=\"rue de la Mont\u00e9e\"  class=\"choice-54 depth-1\"  >rue de la Mont\u00e9e<\/option><option value=\"Op Paasseleck\"  class=\"choice-55 depth-1\"  >Op Paasseleck<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-24662-field_166-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"166\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24662-field_167-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"167\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_167\">Postal code <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24662-field_167\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][167]\" aria-errormessage=\"wpforms-24662-field_167-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24662-field_168-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"168\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_168\">Location <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24662-field_168\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][168]\" required=\"required\"><option value=\"Mamer\"  class=\"choice-1 depth-1\"  >Mamer<\/option><option value=\"Capellen\"  class=\"choice-2 depth-1\"  >Capellen<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-24662-field_172-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"172\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24662-field_175-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"175\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_175\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24662-field_175\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][175]\" aria-errormessage=\"wpforms-24662-field_175-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24662-field_174-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"174\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_174\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-24662-field_174\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][174]\" spellcheck=\"false\" aria-errormessage=\"wpforms-24662-field_174-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24662-field_52-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"52\"><div id=\"wpforms-24662-field_52\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_52-error\"><h5><span style=\"color: #ff0000\">Important information:<\/span><\/h5>\n<p><span style=\"color: #ff0000\">1. The number of permanent stickers is limited to three per household.<br \/>\nA 4th sticker may be issued on payment of an annual fee of \u20ac100.   <\/span><\/p>\n<p><span style=\"color: #ff0000\">2. Each sticker may bear 2 license plate numbers.<br \/>\nNo single license plate number may appear on more than one sticker. <\/span><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24662-field_141-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"141\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-25-25-25-25\"><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24662-field_142-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"142\"><div id=\"wpforms-24662-field_142\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_142-error\"><h4><\/h4>\n<p>&nbsp;<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24662-field_151-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"151\"><div id=\"wpforms-24662-field_151\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_151-error\"><h5>1. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24662-field_152-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"152\"><div id=\"wpforms-24662-field_152\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_152-error\"><h5>2. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24662-field_153-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"153\"><div id=\"wpforms-24662-field_153\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_153-error\"><h5>3. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24662-field_147-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"147\"><div id=\"wpforms-24662-field_147\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_147-error\"><h5>Owner's full name<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24662-field_148-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"148\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_148\" aria-hidden=\"false\">1 Vignette \/ 1st registration number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24662-field_148\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][148]\" aria-errormessage=\"wpforms-24662-field_148-error\" required><\/div><div id=\"wpforms-24662-field_149-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"149\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_149\" aria-hidden=\"false\">2 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24662-field_149\" class=\"wpforms-field-medium\" name=\"wpforms[fields][149]\" aria-errormessage=\"wpforms-24662-field_149-error\" ><\/div><div id=\"wpforms-24662-field_150-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"150\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_150\" aria-hidden=\"false\">3 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24662-field_150\" class=\"wpforms-field-medium\" name=\"wpforms[fields][150]\" aria-errormessage=\"wpforms-24662-field_150-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24662-field_154-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"154\"><div id=\"wpforms-24662-field_154\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_154-error\"><h5>1st registration number<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24662-field_155-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"155\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_155\" aria-hidden=\"false\">1 Vignette \/ 1st registration number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24662-field_155\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][155]\" aria-errormessage=\"wpforms-24662-field_155-error\" required><\/div><div id=\"wpforms-24662-field_156-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"156\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_156\" aria-hidden=\"false\">2 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24662-field_156\" class=\"wpforms-field-medium\" name=\"wpforms[fields][156]\" aria-errormessage=\"wpforms-24662-field_156-error\" ><\/div><div id=\"wpforms-24662-field_157-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"157\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_157\" aria-hidden=\"false\">3 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24662-field_157\" class=\"wpforms-field-medium\" name=\"wpforms[fields][157]\" aria-errormessage=\"wpforms-24662-field_157-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24662-field_158-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"158\"><div id=\"wpforms-24662-field_158\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_158-error\"><h5>2nd registration number (optional)<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24662-field_159-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"159\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_159\" aria-hidden=\"false\">1 Vignette \/ 2nd registration number<\/label><input type=\"text\" id=\"wpforms-24662-field_159\" class=\"wpforms-field-medium\" name=\"wpforms[fields][159]\" aria-errormessage=\"wpforms-24662-field_159-error\" ><\/div><div id=\"wpforms-24662-field_160-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"160\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_160\" aria-hidden=\"false\">2 Vignette \/ 2nd registration number<\/label><input type=\"text\" id=\"wpforms-24662-field_160\" class=\"wpforms-field-medium\" name=\"wpforms[fields][160]\" aria-errormessage=\"wpforms-24662-field_160-error\" ><\/div><div id=\"wpforms-24662-field_161-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"161\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24662-field_161\" aria-hidden=\"false\">3 Vignette \/ 3rd registration number<\/label><input type=\"text\" id=\"wpforms-24662-field_161\" class=\"wpforms-field-medium\" name=\"wpforms[fields][161]\" aria-errormessage=\"wpforms-24662-field_161-error\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-24662-field_59-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"59\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_59\">A copy of the vehicle registration certificate(s) (Carte Grise, Zulassungsbescheinigung) \/ Rental\/leasing contract, if applicable, must be enclosed. <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div\n\t\tclass=\"wpforms-uploader wpforms-field-required\"\n\t\tdata-field-id=\"59\"\n\t\tdata-form-id=\"24662\"\n\t\tdata-input-name=\"wpforms_24662_59\"\n\t\tdata-extensions=\"pdf,doc,docx,png,jpg,jpeg\"\n\t\tdata-max-size=\"67108864\"\n\t\tdata-max-file-number=\"5\"\n\t\tdata-post-max-size=\"67108864\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">You can upload up to 5 files.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-24662-field_59\"\n\t\tname=\"wpforms_24662_59\" required\t\tvalue=\"\">\n<\/div><div id=\"wpforms-24662-field_53-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"53\"><div id=\"wpforms-24662-field_53\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24662-field_53-error\"><h4>Remarks:<\/h4>\n<ul>\n<li>Permanent stickers are renewed automatically towards the end of the year.<\/li>\n<li>Stickers are only valid in the commune of Mamer and only in the area indicated there.<\/li>\n<li>For any changes, the old sticker must be returned to the commune with the necessary documents and information.<\/li>\n<li>Lost or stolen stickers must be reported to the commune as soon as possible.<\/li>\n<li>If you move or sell the vehicle shown on the sticker, it must be returned to the commune without delay.<\/li>\n<li>For a rental\/leasing car or a company car, a copy of the leasing or rental contract (private) issued in your name, or an employer's certificate of private use for a company car made available to you, must be enclosed.<\/li>\n<\/ul>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24662-field_36-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"36\"><label class=\"wpforms-field-label\">RGPD Agreement   <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-24662-field_36\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-24662-field_36_1\" name=\"wpforms[fields][36][]\" value=\"I consent to this site storing my submitted information so that they may respond to my request.\" aria-errormessage=\"wpforms-24662-field_36_1-error\" aria-describedby=\"wpforms-24662-field_36-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-24662-field_36_1\">I consent to this site storing my submitted information so that they may respond to my request.<\/label><\/li><\/ul><div id=\"wpforms-24662-field_36-description\" class=\"wpforms-field-description\">The data collected in this form is necessary for the processing of your file by the services of the Communal Administration, and if necessary by its subcontractors.\nIt is processed fairly and transparently in accordance with the General Data Protection Regulation (RGPD), and kept for the duration necessary for this processing as well as the applicable legal archiving period.\nIf you have any questions about the processing of personal data, you can contact the Data Protection Officer (DPO) at dpo@mamer.lu .  <\/div><\/div><div id=\"wpforms-24662-field_176-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"176\"><label class=\"wpforms-field-label\" for=\"wpforms-24662-field_176\">sigi-field<\/label><input type=\"text\" id=\"wpforms-24662-field_176\" class=\"wpforms-field-medium\" name=\"wpforms[fields][176]\" aria-errormessage=\"wpforms-24662-field_176-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"24662\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-24662\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet ...\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/span><\/p>\n<p><\/p>\n<p><span><style id=\"wpforms-css-vars-24951\">\n\t\t\t\t#wpforms-24951 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-24951\"><form id=\"wpforms-form-24951\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"24951\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761?wpforms_form_id=24951\" data-token=\"c0a346a75f74d62516c02c10d0e5ce19\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-24951-field_169-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"169\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24951-field_170-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"170\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_170\">First name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24951-field_170\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][170]\" aria-errormessage=\"wpforms-24951-field_170-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24951-field_171-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"171\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_171\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24951-field_171\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][171]\" aria-errormessage=\"wpforms-24951-field_171-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24951-field_163-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"163\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24951-field_164-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"164\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_164\">N\u00b0 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24951-field_164\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][164]\" aria-errormessage=\"wpforms-24951-field_164-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24951-field_165-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"165\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_165\">Rue <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24951-field_165\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][165]\" required=\"required\"><option value=\"Domaine Beaulieu\"  class=\"choice-27 depth-1\"  >Domaine Beaulieu<\/option><option value=\"Kitschenerwee\"  class=\"choice-28 depth-1\"  >Kitschenerwee<\/option><option value=\"Place de l&#039;Ind\u00e9pendance\"  class=\"choice-29 depth-1\"  >Place de l'Ind\u00e9pendance<\/option><option value=\"Roudewee\"  class=\"choice-30 depth-1\"  >Roudewee<\/option><option value=\"route d&#039;Arlon\"  class=\"choice-31 depth-1\"  >route d'Arlon<\/option><option value=\"route de Dippach\"  class=\"choice-32 depth-1\"  >route de Dippach<\/option><option value=\"route de Kehlen\"  class=\"choice-33 depth-1\"  >route de Kehlen<\/option><option value=\"rue Anna Lindh\"  class=\"choice-34 depth-1\"  >rue Anna Lindh<\/option><option value=\"rue Anne Beffort\"  class=\"choice-35 depth-1\"  >rue Anne Beffort<\/option><option value=\"rue Belle-Vue\"  class=\"choice-36 depth-1\"  >rue Belle-Vue<\/option><option value=\"rue Cun\u00e9gonde\"  class=\"choice-37 depth-1\"  >rue Cun\u00e9gonde<\/option><option value=\"rue de Bertrange\"  class=\"choice-38 depth-1\"  >rue de Bertrange<\/option><option value=\"rue de Dang\u00e9-St-Romain\"  class=\"choice-39 depth-1\"  >rue de Dang\u00e9-St-Romain<\/option><option value=\"rue de la Gare\"  class=\"choice-40 depth-1\"  >rue de la Gare<\/option><option value=\"rue de la Lib\u00e9ration\"  class=\"choice-41 depth-1\"  >rue de la Lib\u00e9ration<\/option><option value=\"rue de l&#039;Ecole\"  class=\"choice-42 depth-1\"  >rue de l'Ecole<\/option><option value=\"rue des Maximins\"  class=\"choice-43 depth-1\"  >rue des Maximins<\/option><option value=\"rue des Pr\u00e9s\"  class=\"choice-44 depth-1\"  >rue des Pr\u00e9s<\/option><option value=\"rue des Roses\"  class=\"choice-45 depth-1\"  >rue des Roses<\/option><option value=\"rue du Baerendall\"  class=\"choice-46 depth-1\"  >rue du Baerendall<\/option><option value=\"rue du Centre\"  class=\"choice-47 depth-1\"  >rue du Centre<\/option><option value=\"rue du Commerce\"  class=\"choice-48 depth-1\"  >rue du Commerce<\/option><option value=\"rue du March\u00e9\"  class=\"choice-49 depth-1\"  >rue du March\u00e9<\/option><option value=\"rue du Mill\u00e9naire\"  class=\"choice-50 depth-1\"  >rue du Mill\u00e9naire<\/option><option value=\"rue Elsy Jacobs\"  class=\"choice-51 depth-1\"  >rue Elsy Jacobs<\/option><option value=\"rue Ermesinde\"  class=\"choice-52 depth-1\"  >rue Ermesinde<\/option><option value=\"rue Fran\u00e7ois Trausch\"  class=\"choice-53 depth-1\"  >rue Fran\u00e7ois Trausch<\/option><option value=\"rue Gaaschtbierg\"  class=\"choice-54 depth-1\"  >rue Gaaschtbierg<\/option><option value=\"rue Golda Meir\"  class=\"choice-55 depth-1\"  >rue Golda Meir<\/option><option value=\"rue Henri Kirpach\"  class=\"choice-56 depth-1\"  >rue Henri Kirpach<\/option><option value=\"rue Indira Gandhi\"  class=\"choice-57 depth-1\"  >rue Indira Gandhi<\/option><option value=\"rue Jo Cox\"  class=\"choice-58 depth-1\"  >rue Jo Cox<\/option><option value=\"rue Josy Barthel\"  class=\"choice-59 depth-1\"  >rue Josy Barthel<\/option><option value=\"rue Karewee\"  class=\"choice-60 depth-1\"  >rue Karewee<\/option><option value=\"rue Klengliller\"  class=\"choice-61 depth-1\"  >rue Klengliller<\/option><option value=\"rue Kneppchen\"  class=\"choice-62 depth-1\"  >rue Kneppchen<\/option><option value=\"rue Madeleine Frieden-Kinnen\"  class=\"choice-63 depth-1\"  >rue Madeleine Frieden-Kinnen<\/option><option value=\"rue Mambra\"  class=\"choice-64 depth-1\"  >rue Mambra<\/option><option value=\"rue Mameranus\"  class=\"choice-65 depth-1\"  >rue Mameranus<\/option><option value=\"rue Margaret Thatcher\"  class=\"choice-66 depth-1\"  >rue Margaret Thatcher<\/option><option value=\"rue Marie-Paule Molitor-Peffer\"  class=\"choice-67 depth-1\"  >rue Marie-Paule Molitor-Peffer<\/option><option value=\"rue Nicolas Frantz\"  class=\"choice-68 depth-1\"  >rue Nicolas Frantz<\/option><option value=\"rue Op Bierg\"  class=\"choice-69 depth-1\"  >rue Op Bierg<\/option><option value=\"rue Pierre Krier-Becker\"  class=\"choice-70 depth-1\"  >rue Pierre Krier-Becker<\/option><option value=\"rue Raoul Follereau\"  class=\"choice-71 depth-1\"  >rue Raoul Follereau<\/option><option value=\"rue Sigefroi\"  class=\"choice-72 depth-1\"  >rue Sigefroi<\/option><option value=\"rue Simone Veil\"  class=\"choice-73 depth-1\"  >rue Simone Veil<\/option><option value=\"rue Wieseck\"  class=\"choice-74 depth-1\"  >rue Wieseck<\/option><option value=\"rue Yolande\"  class=\"choice-75 depth-1\"  >rue Yolande<\/option><option value=\"Thommeg\u00e4ssel\"  class=\"choice-76 depth-1\"  >Thommeg\u00e4ssel<\/option><option value=\"rue de la Mont\u00e9e\"  class=\"choice-77 depth-1\"  >rue de la Mont\u00e9e<\/option><option value=\"Op Paasseleck\"  class=\"choice-78 depth-1\"  >Op Paasseleck<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-24951-field_166-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"166\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24951-field_167-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"167\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_167\">Postal code <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24951-field_167\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][167]\" aria-errormessage=\"wpforms-24951-field_167-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24951-field_168-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"168\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_168\">Location <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24951-field_168\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][168]\" required=\"required\"><option value=\"Mamer\"  class=\"choice-1 depth-1\"  >Mamer<\/option><option value=\"Capellen\"  class=\"choice-2 depth-1\"  >Capellen<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-24951-field_172-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"172\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24951-field_175-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"175\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_175\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24951-field_175\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][175]\" aria-errormessage=\"wpforms-24951-field_175-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24951-field_174-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"174\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_174\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-24951-field_174\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][174]\" spellcheck=\"false\" aria-errormessage=\"wpforms-24951-field_174-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24951-field_52-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"52\"><div id=\"wpforms-24951-field_52\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_52-error\"><p>hereby requests the issuance of residential parking stickers for the following vehicles<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_141-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"141\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-25-25-25-25\"><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24951-field_142-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"142\"><div id=\"wpforms-24951-field_142\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_142-error\"><h4><\/h4>\n<p>&nbsp;<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_151-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"151\"><div id=\"wpforms-24951-field_151\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_151-error\"><h5>1. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_152-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"152\"><div id=\"wpforms-24951-field_152\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_152-error\"><h5>2. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_153-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"153\"><div id=\"wpforms-24951-field_153\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_153-error\"><h5>3. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24951-field_147-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"147\"><div id=\"wpforms-24951-field_147\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_147-error\"><h5>Owner's full name<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_148-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"148\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_148\" aria-hidden=\"false\">1 Vignette \/ 1st registration number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24951-field_148\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][148]\" aria-errormessage=\"wpforms-24951-field_148-error\" required><\/div><div id=\"wpforms-24951-field_149-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"149\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_149\" aria-hidden=\"false\">2 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24951-field_149\" class=\"wpforms-field-medium\" name=\"wpforms[fields][149]\" aria-errormessage=\"wpforms-24951-field_149-error\" ><\/div><div id=\"wpforms-24951-field_150-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"150\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_150\" aria-hidden=\"false\">3 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24951-field_150\" class=\"wpforms-field-medium\" name=\"wpforms[fields][150]\" aria-errormessage=\"wpforms-24951-field_150-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24951-field_154-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"154\"><div id=\"wpforms-24951-field_154\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_154-error\"><h5>1st registration number<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_155-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"155\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_155\" aria-hidden=\"false\">1 Vignette \/ 1st registration number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24951-field_155\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][155]\" aria-errormessage=\"wpforms-24951-field_155-error\" required><\/div><div id=\"wpforms-24951-field_156-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"156\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_156\" aria-hidden=\"false\">2 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24951-field_156\" class=\"wpforms-field-medium\" name=\"wpforms[fields][156]\" aria-errormessage=\"wpforms-24951-field_156-error\" ><\/div><div id=\"wpforms-24951-field_157-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"157\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_157\" aria-hidden=\"false\">3 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24951-field_157\" class=\"wpforms-field-medium\" name=\"wpforms[fields][157]\" aria-errormessage=\"wpforms-24951-field_157-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24951-field_158-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"158\"><div id=\"wpforms-24951-field_158\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_158-error\"><h5>2nd registration number (optional)<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_159-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"159\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_159\" aria-hidden=\"false\">1 Vignette \/ 2nd registration number<\/label><input type=\"text\" id=\"wpforms-24951-field_159\" class=\"wpforms-field-medium\" name=\"wpforms[fields][159]\" aria-errormessage=\"wpforms-24951-field_159-error\" ><\/div><div id=\"wpforms-24951-field_160-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"160\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_160\" aria-hidden=\"false\">2 Vignette \/ 2nd registration number<\/label><input type=\"text\" id=\"wpforms-24951-field_160\" class=\"wpforms-field-medium\" name=\"wpforms[fields][160]\" aria-errormessage=\"wpforms-24951-field_160-error\" ><\/div><div id=\"wpforms-24951-field_161-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"161\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24951-field_161\" aria-hidden=\"false\">3 Vignette \/ 3rd registration number<\/label><input type=\"text\" id=\"wpforms-24951-field_161\" class=\"wpforms-field-medium\" name=\"wpforms[fields][161]\" aria-errormessage=\"wpforms-24951-field_161-error\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-24951-field_180-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"180\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_180\">Dur\u00e9e de validit\u00e9: (max 6 mois) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24951-field_180\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][180]\" required=\"required\"><option value=\"1 mois\"  class=\"choice-1 depth-1\"  >1 mois<\/option><option value=\"2 mois\"  class=\"choice-2 depth-1\"  >2 mois<\/option><option value=\"3 mois\"  class=\"choice-3 depth-1\"  >3 mois<\/option><option value=\"4 mois\"  class=\"choice-6 depth-1\"  >4 mois<\/option><option value=\"5 mois\"  class=\"choice-5 depth-1\"  >5 mois<\/option><option value=\"6 mois\"  class=\"choice-4 depth-1\"  >6 mois<\/option><\/select><\/div><div id=\"wpforms-24951-field_176-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"176\"><div id=\"wpforms-24951-field_176\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_176-error\"><h4><span style=\"color: #ff0000\">Important information:<\/span><\/h4>\n<p><span style=\"color: #ff0000\">1. The application must be accompanied by a copy of the vehicle registration certificate (Zulassungsbescheinigung).<\/span><span style=\"color: #ff0000\">2. In the case of a rental\/leasing car, the rental contract must be attached to the application.<\/span><span style=\"color: #ff0000\">3. No registration number may appear on more than one sticker.<\/span><span style=\"color: #ff0000\">4. The number of stickers is limited to three per household.&nbsp;<\/span><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_59-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"59\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_59\">A copy of the vehicle registration certificate(s) (Carte Grise, Zulassungsbescheinigung) \/ Rental\/leasing contract, if applicable, must be enclosed. <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div\n\t\tclass=\"wpforms-uploader wpforms-field-required\"\n\t\tdata-field-id=\"59\"\n\t\tdata-form-id=\"24951\"\n\t\tdata-input-name=\"wpforms_24951_59\"\n\t\tdata-extensions=\"pdf,doc,docx,png,jpg\"\n\t\tdata-max-size=\"67108864\"\n\t\tdata-max-file-number=\"5\"\n\t\tdata-post-max-size=\"67108864\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">You can upload up to 5 files.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-24951-field_59\"\n\t\tname=\"wpforms_24951_59\" required\t\tvalue=\"\">\n<\/div><div id=\"wpforms-24951-field_53-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"53\"><div id=\"wpforms-24951-field_53\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24951-field_53-error\"><h4>Remarks:<\/h4>\n<ul>\n<li>The temporary sticker can be issued for a period of 1 to 6 months.<\/li>\n<li>The temporary sticker issued for a car registered abroad is valid for a maximum of 6 months and cannot be extended.<\/li>\n<li>Lost or stolen stickers must be reported to the commune as soon as possible.<\/li>\n<li>If you move or sell the vehicle shown on the sticker, it must be returned to the commune without delay.<\/li>\n<li>All forms relating to residential parking can be downloaded from our website <a href=\"https:\/\/mamer.lu\/formulaires\">www.mamer.lu\/formulaires<\/a> or requested from the municipal administration.<\/li>\n<\/ul>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24951-field_36-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"36\"><label class=\"wpforms-field-label\">RGPD Agreement   <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-24951-field_36\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-24951-field_36_1\" name=\"wpforms[fields][36][]\" value=\"I consent to this site storing my submitted information so that they may respond to my request.\" aria-errormessage=\"wpforms-24951-field_36_1-error\" aria-describedby=\"wpforms-24951-field_36-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-24951-field_36_1\">I consent to this site storing my submitted information so that they may respond to my request.<\/label><\/li><\/ul><div id=\"wpforms-24951-field_36-description\" class=\"wpforms-field-description\">The data collected in this form is necessary for the processing of your file by the services of the Communal Administration, and if necessary by its subcontractors.\nIt is processed fairly and transparently in accordance with the General Data Protection Regulation (RGPD), and kept for the duration necessary for this processing as well as the applicable legal archiving period.\nIf you have any questions about the processing of personal data, you can contact the Data Protection Officer (DPO) at dpo@mamer.lu .  <\/div><\/div><div id=\"wpforms-24951-field_177-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"177\"><label class=\"wpforms-field-label\" for=\"wpforms-24951-field_177\">sigi-field<\/label><input type=\"text\" id=\"wpforms-24951-field_177\" class=\"wpforms-field-medium\" name=\"wpforms[fields][177]\" aria-errormessage=\"wpforms-24951-field_177-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"24951\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-24951\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet ...\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --> <\/span><\/p>\n<p><\/p>\n<p><span><style id=\"wpforms-css-vars-24976\">\n\t\t\t\t#wpforms-24976 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-24976\"><form id=\"wpforms-form-24976\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"24976\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761?wpforms_form_id=24976\" data-token=\"37354696654eab6386f5d482a2475991\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-24976-field_53-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"53\"><div id=\"wpforms-24976-field_53\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24976-field_53-error\"><h4>Remarks:<\/h4>\n<ul>\n<li><strong>A visitor's permit may be requested by residents of a sector subject to residential parking regulations, for the benefit of persons who are not residents of the municipality\/sector in question, when these persons are staying with the applicant for an extended period within the framework of family relationships.<\/strong><\/li>\n<li><strong>A maximum of 3 visitor stickers may be issued for a minimum period of 1 week per sticker, per household and per year. However, the maximum cumulative duration (of the 3 stickers) may not exceed 3 months per household per year. <\/strong><\/li>\n<li><strong>For a rental\/leasing car or a company car, a copy of the leasing or rental contract (private) issued in your name, or an employer's certificate of private use for a company car made available to you, must be enclosed.<\/strong><\/li>\n<\/ul>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24976-field_169-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"169\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_170-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"170\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_170\">First name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_170\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][170]\" aria-errormessage=\"wpforms-24976-field_170-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24976-field_171-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"171\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_171\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_171\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][171]\" aria-errormessage=\"wpforms-24976-field_171-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24976-field_163-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"163\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_164-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"164\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_164\">N\u00b0 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_164\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][164]\" aria-errormessage=\"wpforms-24976-field_164-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24976-field_165-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"165\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_165\">Rue <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24976-field_165\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][165]\" required=\"required\"><option value=\"Domaine Beaulieu\"  selected='selected' class=\"choice-27 depth-1\"  >Domaine Beaulieu<\/option><option value=\"Kitschenerwee\"  class=\"choice-28 depth-1\"  >Kitschenerwee<\/option><option value=\"Place de l&#039;Ind\u00e9pendance\"  class=\"choice-29 depth-1\"  >Place de l'Ind\u00e9pendance<\/option><option value=\"Roudewee\"  class=\"choice-30 depth-1\"  >Roudewee<\/option><option value=\"route d&#039;Arlon\"  class=\"choice-31 depth-1\"  >route d'Arlon<\/option><option value=\"route de Dippach\"  class=\"choice-32 depth-1\"  >route de Dippach<\/option><option value=\"route de Kehlen\"  class=\"choice-33 depth-1\"  >route de Kehlen<\/option><option value=\"rue Anna Lindh\"  class=\"choice-34 depth-1\"  >rue Anna Lindh<\/option><option value=\"rue Anne Beffort\"  class=\"choice-35 depth-1\"  >rue Anne Beffort<\/option><option value=\"rue Belle-Vue\"  class=\"choice-36 depth-1\"  >rue Belle-Vue<\/option><option value=\"rue Cun\u00e9gonde\"  class=\"choice-37 depth-1\"  >rue Cun\u00e9gonde<\/option><option value=\"rue de Bertrange\"  class=\"choice-38 depth-1\"  >rue de Bertrange<\/option><option value=\"rue de Dang\u00e9-St-Romain\"  class=\"choice-39 depth-1\"  >rue de Dang\u00e9-St-Romain<\/option><option value=\"rue de la Gare\"  class=\"choice-40 depth-1\"  >rue de la Gare<\/option><option value=\"rue de la Lib\u00e9ration\"  class=\"choice-41 depth-1\"  >rue de la Lib\u00e9ration<\/option><option value=\"rue de l&#039;Ecole\"  class=\"choice-42 depth-1\"  >rue de l'Ecole<\/option><option value=\"rue des Maximins\"  class=\"choice-43 depth-1\"  >rue des Maximins<\/option><option value=\"rue des Pr\u00e9s\"  class=\"choice-44 depth-1\"  >rue des Pr\u00e9s<\/option><option value=\"rue des Roses\"  class=\"choice-45 depth-1\"  >rue des Roses<\/option><option value=\"rue du Baerendall\"  class=\"choice-46 depth-1\"  >rue du Baerendall<\/option><option value=\"rue du Centre\"  class=\"choice-47 depth-1\"  >rue du Centre<\/option><option value=\"rue du Commerce\"  class=\"choice-48 depth-1\"  >rue du Commerce<\/option><option value=\"rue du March\u00e9\"  class=\"choice-49 depth-1\"  >rue du March\u00e9<\/option><option value=\"rue du Mill\u00e9naire\"  class=\"choice-50 depth-1\"  >rue du Mill\u00e9naire<\/option><option value=\"rue Elsy Jacobs\"  class=\"choice-51 depth-1\"  >rue Elsy Jacobs<\/option><option value=\"rue Ermesinde\"  class=\"choice-52 depth-1\"  >rue Ermesinde<\/option><option value=\"rue Fran\u00e7ois Trausch\"  class=\"choice-53 depth-1\"  >rue Fran\u00e7ois Trausch<\/option><option value=\"rue Gaaschtbierg\"  class=\"choice-54 depth-1\"  >rue Gaaschtbierg<\/option><option value=\"rue Golda Meir\"  class=\"choice-55 depth-1\"  >rue Golda Meir<\/option><option value=\"rue Henri Kirpach\"  class=\"choice-56 depth-1\"  >rue Henri Kirpach<\/option><option value=\"rue Indira Gandhi\"  class=\"choice-57 depth-1\"  >rue Indira Gandhi<\/option><option value=\"rue Jo Cox\"  class=\"choice-58 depth-1\"  >rue Jo Cox<\/option><option value=\"rue Josy Barthel\"  class=\"choice-59 depth-1\"  >rue Josy Barthel<\/option><option value=\"rue Karewee\"  class=\"choice-60 depth-1\"  >rue Karewee<\/option><option value=\"rue Klengliller\"  class=\"choice-61 depth-1\"  >rue Klengliller<\/option><option value=\"rue Kneppchen\"  class=\"choice-62 depth-1\"  >rue Kneppchen<\/option><option value=\"rue Madeleine Frieden-Kinnen\"  class=\"choice-63 depth-1\"  >rue Madeleine Frieden-Kinnen<\/option><option value=\"rue Mambra\"  class=\"choice-64 depth-1\"  >rue Mambra<\/option><option value=\"rue Mameranus\"  class=\"choice-65 depth-1\"  >rue Mameranus<\/option><option value=\"rue Margaret Thatcher\"  class=\"choice-66 depth-1\"  >rue Margaret Thatcher<\/option><option value=\"rue Marie-Paule Molitor-Peffer\"  class=\"choice-67 depth-1\"  >rue Marie-Paule Molitor-Peffer<\/option><option value=\"rue Nicolas Frantz\"  class=\"choice-68 depth-1\"  >rue Nicolas Frantz<\/option><option value=\"rue Op Bierg\"  class=\"choice-69 depth-1\"  >rue Op Bierg<\/option><option value=\"rue Pierre Krier-Becker\"  class=\"choice-70 depth-1\"  >rue Pierre Krier-Becker<\/option><option value=\"rue Raoul Follereau\"  class=\"choice-71 depth-1\"  >rue Raoul Follereau<\/option><option value=\"rue Sigefroi\"  class=\"choice-72 depth-1\"  >rue Sigefroi<\/option><option value=\"rue Simone Veil\"  class=\"choice-73 depth-1\"  >rue Simone Veil<\/option><option value=\"rue Wieseck\"  class=\"choice-74 depth-1\"  >rue Wieseck<\/option><option value=\"rue Yolande\"  class=\"choice-75 depth-1\"  >rue Yolande<\/option><option value=\"rue de la Mont\u00e9e\"  class=\"choice-76 depth-1\"  >rue de la Mont\u00e9e<\/option><option value=\"Op Paasseleck\"  class=\"choice-77 depth-1\"  >Op Paasseleck<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-24976-field_166-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"166\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_167-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"167\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_167\">Postal code <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_167\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][167]\" aria-errormessage=\"wpforms-24976-field_167-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24976-field_168-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"168\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_168\">Location <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24976-field_168\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][168]\" required=\"required\"><option value=\"Mamer\"  class=\"choice-1 depth-1\"  >Mamer<\/option><option value=\"Capellen\"  class=\"choice-2 depth-1\"  >Capellen<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-24976-field_172-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"172\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_175-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"175\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_175\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_175\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][175]\" aria-errormessage=\"wpforms-24976-field_175-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24976-field_174-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"174\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_174\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-24976-field_174\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][174]\" spellcheck=\"false\" aria-errormessage=\"wpforms-24976-field_174-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24976-field_52-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"52\"><div id=\"wpforms-24976-field_52\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24976-field_52-error\"><p><strong>hereby declares that<\/strong><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24976-field_178-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"178\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_179-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"179\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_179\">First name (visitor) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_179\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][179]\" aria-errormessage=\"wpforms-24976-field_179-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24976-field_180-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"180\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_180\">Name (visitor) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_180\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][180]\" aria-errormessage=\"wpforms-24976-field_180-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24976-field_204-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"204\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_205-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"205\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_205\">N\u00b0 (visitor) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_205\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][205]\" aria-errormessage=\"wpforms-24976-field_205-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24976-field_207-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"207\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_207\">Street (visitor) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_207\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][207]\" aria-errormessage=\"wpforms-24976-field_207-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24976-field_208-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"208\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-33-33\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_209-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"209\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_209\">Postal code (visitor) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_209\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][209]\" aria-errormessage=\"wpforms-24976-field_209-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_210-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"210\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_210\">Location (visitor) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_210\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][210]\" aria-errormessage=\"wpforms-24976-field_210-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_219-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"219\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_219\">Country (visitor) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_219\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][219]\" aria-errormessage=\"wpforms-24976-field_219-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24976-field_189-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"189\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24976-field_190-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"190\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_190\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_190\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][190]\" aria-errormessage=\"wpforms-24976-field_190-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24976-field_191-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"191\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_191\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-24976-field_191\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][191]\" spellcheck=\"false\" aria-errormessage=\"wpforms-24976-field_191-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24976-field_199-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"199\"><div id=\"wpforms-24976-field_199\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24976-field_199-error\"><p><strong>comes to stay with the  <\/strong><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24976-field_211-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"211\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-25-25-25-25\"><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24976-field_214-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"214\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_214\">Start date <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-24976-field_214\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"1\" data-disable-todays-date=\"0\" data-input=\"true\" name=\"wpforms[fields][214][date]\" aria-errormessage=\"wpforms-24976-field_214-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24976-field_217-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"217\"><div id=\"wpforms-24976-field_217\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24976-field_217-error\"><p><strong>at<\/strong><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24976-field_218-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"218\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_218\">End date <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-24976-field_218\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"1\" data-disable-todays-date=\"0\" data-input=\"true\" name=\"wpforms[fields][218][date]\" aria-errormessage=\"wpforms-24976-field_218-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><\/div><\/div><\/div><div id=\"wpforms-24976-field_213-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"213\"><div id=\"wpforms-24976-field_213\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24976-field_213-error\"><p><strong>and therefore requests a \"visitor\" sticker for this period for the following vehicle:<\/strong><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24976-field_141-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"141\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-25-25-25-25\"><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24976-field_185-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"185\"><div id=\"wpforms-24976-field_185\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24976-field_185-error\"><h5>Make \/ Model<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24976-field_148-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"148\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24976-field_148\" aria-hidden=\"false\">Make \/ Model <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_148\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][148]\" aria-errormessage=\"wpforms-24976-field_148-error\" required><\/div><div id=\"wpforms-24976-field_142-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"142\"><div id=\"wpforms-24976-field_142\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24976-field_142-error\"><h4><\/h4>\n<p>&nbsp;<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24976-field_154-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"154\"><div id=\"wpforms-24976-field_154\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24976-field_154-error\"><h5>Registration number<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24976-field_155-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"155\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24976-field_155\" aria-hidden=\"false\">Registration number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24976-field_155\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][155]\" aria-errormessage=\"wpforms-24976-field_155-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><\/div><\/div><\/div><div id=\"wpforms-24976-field_59-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"59\"><label class=\"wpforms-field-label\" for=\"wpforms-24976-field_59\">Important: The application must be accompanied by a copy of the vehicle registration document (Zulassungsbescheinigung).d&#039;immatriculation (carte grise, Zulassungsbescheinigung) \/ Rental\/leasing contract where applicable <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div\n\t\tclass=\"wpforms-uploader wpforms-field-required\"\n\t\tdata-field-id=\"59\"\n\t\tdata-form-id=\"24976\"\n\t\tdata-input-name=\"wpforms_24976_59\"\n\t\tdata-extensions=\"pdf,doc,docx,png,jpg\"\n\t\tdata-max-size=\"67108864\"\n\t\tdata-max-file-number=\"5\"\n\t\tdata-post-max-size=\"67108864\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">You can upload up to 5 files.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-24976-field_59\"\n\t\tname=\"wpforms_24976_59\" required\t\tvalue=\"\">\n<\/div><div id=\"wpforms-24976-field_36-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"36\"><label class=\"wpforms-field-label\">RGPD Agreement   <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-24976-field_36\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-24976-field_36_1\" name=\"wpforms[fields][36][]\" value=\"I consent to this site storing my submitted information so that they may respond to my request.\" aria-errormessage=\"wpforms-24976-field_36_1-error\" aria-describedby=\"wpforms-24976-field_36-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-24976-field_36_1\">I consent to this site storing my submitted information so that they may respond to my request.<\/label><\/li><\/ul><div id=\"wpforms-24976-field_36-description\" class=\"wpforms-field-description\">The data collected in this form is necessary for the processing of your file by the services of the Communal Administration, and if necessary by its subcontractors.\nIt is processed fairly and transparently in accordance with the General Data Protection Regulation (RGPD), and kept for the duration necessary for this processing as well as the applicable legal archiving period.\nIf you have any questions about the processing of personal data, you can contact the Data Protection Officer (DPO) at dpo@mamer.lu .  <\/div><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"24976\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-24976\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet ...\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --> <\/span><\/p>\n<p><\/p>\n<p><span><style id=\"wpforms-css-vars-24968\">\n\t\t\t\t#wpforms-24968 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-24968\"><form id=\"wpforms-form-24968\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"24968\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761?wpforms_form_id=24968\" data-token=\"209ddd7f6b53c3dee81f8322339b641c\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-24968-field_169-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"169\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24968-field_170-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"170\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_170\">First name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24968-field_170\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][170]\" aria-errormessage=\"wpforms-24968-field_170-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24968-field_171-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"171\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_171\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24968-field_171\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][171]\" aria-errormessage=\"wpforms-24968-field_171-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24968-field_163-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"163\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24968-field_164-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"164\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_164\">N\u00b0 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24968-field_164\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][164]\" aria-errormessage=\"wpforms-24968-field_164-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24968-field_165-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"165\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_165\">Rue <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24968-field_165\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][165]\" required=\"required\"><option value=\"Domaine Beaulieu\"  selected='selected' class=\"choice-27 depth-1\"  >Domaine Beaulieu<\/option><option value=\"Kitschenerwee\"  class=\"choice-28 depth-1\"  >Kitschenerwee<\/option><option value=\"Place de l&#039;Ind\u00e9pendance\"  class=\"choice-29 depth-1\"  >Place de l'Ind\u00e9pendance<\/option><option value=\"Roudewee\"  class=\"choice-30 depth-1\"  >Roudewee<\/option><option value=\"route d&#039;Arlon\"  class=\"choice-31 depth-1\"  >route d'Arlon<\/option><option value=\"route de Dippach\"  class=\"choice-32 depth-1\"  >route de Dippach<\/option><option value=\"route de Kehlen\"  class=\"choice-33 depth-1\"  >route de Kehlen<\/option><option value=\"rue Anna Lindh\"  class=\"choice-34 depth-1\"  >rue Anna Lindh<\/option><option value=\"rue Anne Beffort\"  class=\"choice-35 depth-1\"  >rue Anne Beffort<\/option><option value=\"rue Belle-Vue\"  class=\"choice-36 depth-1\"  >rue Belle-Vue<\/option><option value=\"rue Cun\u00e9gonde\"  class=\"choice-37 depth-1\"  >rue Cun\u00e9gonde<\/option><option value=\"rue de Bertrange\"  class=\"choice-38 depth-1\"  >rue de Bertrange<\/option><option value=\"rue de Dang\u00e9-St-Romain\"  class=\"choice-39 depth-1\"  >rue de Dang\u00e9-St-Romain<\/option><option value=\"rue de la Gare\"  class=\"choice-40 depth-1\"  >rue de la Gare<\/option><option value=\"rue de la Lib\u00e9ration\"  class=\"choice-41 depth-1\"  >rue de la Lib\u00e9ration<\/option><option value=\"rue de l&#039;Ecole\"  class=\"choice-42 depth-1\"  >rue de l'Ecole<\/option><option value=\"rue des Maximins\"  class=\"choice-43 depth-1\"  >rue des Maximins<\/option><option value=\"rue des Pr\u00e9s\"  class=\"choice-44 depth-1\"  >rue des Pr\u00e9s<\/option><option value=\"rue des Roses\"  class=\"choice-45 depth-1\"  >rue des Roses<\/option><option value=\"rue du Baerendall\"  class=\"choice-46 depth-1\"  >rue du Baerendall<\/option><option value=\"rue du Centre\"  class=\"choice-47 depth-1\"  >rue du Centre<\/option><option value=\"rue du Commerce\"  class=\"choice-48 depth-1\"  >rue du Commerce<\/option><option value=\"rue du March\u00e9\"  class=\"choice-49 depth-1\"  >rue du March\u00e9<\/option><option value=\"rue du Mill\u00e9naire\"  class=\"choice-50 depth-1\"  >rue du Mill\u00e9naire<\/option><option value=\"rue Elsy Jacobs\"  class=\"choice-51 depth-1\"  >rue Elsy Jacobs<\/option><option value=\"rue Ermesinde\"  class=\"choice-52 depth-1\"  >rue Ermesinde<\/option><option value=\"rue Fran\u00e7ois Trausch\"  class=\"choice-53 depth-1\"  >rue Fran\u00e7ois Trausch<\/option><option value=\"rue Gaaschtbierg\"  class=\"choice-54 depth-1\"  >rue Gaaschtbierg<\/option><option value=\"rue Golda Meir\"  class=\"choice-55 depth-1\"  >rue Golda Meir<\/option><option value=\"rue Henri Kirpach\"  class=\"choice-56 depth-1\"  >rue Henri Kirpach<\/option><option value=\"rue Indira Gandhi\"  class=\"choice-57 depth-1\"  >rue Indira Gandhi<\/option><option value=\"rue Jo Cox\"  class=\"choice-58 depth-1\"  >rue Jo Cox<\/option><option value=\"rue Josy Barthel\"  class=\"choice-59 depth-1\"  >rue Josy Barthel<\/option><option value=\"rue Karewee\"  class=\"choice-60 depth-1\"  >rue Karewee<\/option><option value=\"rue Klengliller\"  class=\"choice-61 depth-1\"  >rue Klengliller<\/option><option value=\"rue Kneppchen\"  class=\"choice-62 depth-1\"  >rue Kneppchen<\/option><option value=\"rue Madeleine Frieden-Kinnen\"  class=\"choice-63 depth-1\"  >rue Madeleine Frieden-Kinnen<\/option><option value=\"rue Mambra\"  class=\"choice-64 depth-1\"  >rue Mambra<\/option><option value=\"rue Mameranus\"  class=\"choice-65 depth-1\"  >rue Mameranus<\/option><option value=\"rue Margaret Thatcher\"  class=\"choice-66 depth-1\"  >rue Margaret Thatcher<\/option><option value=\"rue Marie-Paule Molitor-Peffer\"  class=\"choice-67 depth-1\"  >rue Marie-Paule Molitor-Peffer<\/option><option value=\"rue Nicolas Frantz\"  class=\"choice-68 depth-1\"  >rue Nicolas Frantz<\/option><option value=\"rue Op Bierg\"  class=\"choice-69 depth-1\"  >rue Op Bierg<\/option><option value=\"rue Pierre Krier-Becker\"  class=\"choice-70 depth-1\"  >rue Pierre Krier-Becker<\/option><option value=\"rue Raoul Follereau\"  class=\"choice-71 depth-1\"  >rue Raoul Follereau<\/option><option value=\"rue Sigefroi\"  class=\"choice-72 depth-1\"  >rue Sigefroi<\/option><option value=\"rue Simone Veil\"  class=\"choice-73 depth-1\"  >rue Simone Veil<\/option><option value=\"rue Wieseck\"  class=\"choice-74 depth-1\"  >rue Wieseck<\/option><option value=\"rue Yolande\"  class=\"choice-75 depth-1\"  >rue Yolande<\/option><option value=\"rue de la Mont\u00e9e\"  class=\"choice-76 depth-1\"  >rue de la Mont\u00e9e<\/option><option value=\"Op Paasseleck\"  class=\"choice-77 depth-1\"  >Op Paasseleck<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-24968-field_166-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"166\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24968-field_167-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"167\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_167\">Postal code <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24968-field_167\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][167]\" aria-errormessage=\"wpforms-24968-field_167-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24968-field_168-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"168\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_168\">Location <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-24968-field_168\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][168]\" required=\"required\"><option value=\"Mamer\"  class=\"choice-1 depth-1\"  >Mamer<\/option><option value=\"Capellen\"  class=\"choice-2 depth-1\"  >Capellen<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-24968-field_172-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"172\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-24968-field_175-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"175\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_175\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24968-field_175\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][175]\" aria-errormessage=\"wpforms-24968-field_175-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-24968-field_174-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"174\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_174\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-24968-field_174\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][174]\" spellcheck=\"false\" aria-errormessage=\"wpforms-24968-field_174-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-24968-field_52-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"52\"><div id=\"wpforms-24968-field_52\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_52-error\"><p>hereby requests the issuance of residential parking stickers for the following vehicles<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_141-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"141\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-25-25-25-25\"><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24968-field_142-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"142\"><div id=\"wpforms-24968-field_142\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_142-error\"><h4><\/h4>\n<p>&nbsp;<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_151-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"151\"><div id=\"wpforms-24968-field_151\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_151-error\"><h5>1. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_152-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"152\"><div id=\"wpforms-24968-field_152\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_152-error\"><h5>2. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_153-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"153\"><div id=\"wpforms-24968-field_153\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_153-error\"><h5>3. Vignette<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24968-field_147-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"147\"><div id=\"wpforms-24968-field_147\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_147-error\"><h5>Owner's full name<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_148-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"148\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_148\" aria-hidden=\"false\">1 Vignette \/ 1st registration number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24968-field_148\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][148]\" aria-errormessage=\"wpforms-24968-field_148-error\" required><\/div><div id=\"wpforms-24968-field_149-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"149\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_149\" aria-hidden=\"false\">2 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24968-field_149\" class=\"wpforms-field-medium\" name=\"wpforms[fields][149]\" aria-errormessage=\"wpforms-24968-field_149-error\" ><\/div><div id=\"wpforms-24968-field_150-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"150\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_150\" aria-hidden=\"false\">3 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24968-field_150\" class=\"wpforms-field-medium\" name=\"wpforms[fields][150]\" aria-errormessage=\"wpforms-24968-field_150-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24968-field_154-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"154\"><div id=\"wpforms-24968-field_154\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_154-error\"><h5>1st registration number<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_155-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"155\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_155\" aria-hidden=\"false\">1 Vignette \/ 1st registration number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-24968-field_155\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][155]\" aria-errormessage=\"wpforms-24968-field_155-error\" required><\/div><div id=\"wpforms-24968-field_156-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"156\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_156\" aria-hidden=\"false\">2 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24968-field_156\" class=\"wpforms-field-medium\" name=\"wpforms[fields][156]\" aria-errormessage=\"wpforms-24968-field_156-error\" ><\/div><div id=\"wpforms-24968-field_157-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"157\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_157\" aria-hidden=\"false\">3 Vignette \/ 1st registration number<\/label><input type=\"text\" id=\"wpforms-24968-field_157\" class=\"wpforms-field-medium\" name=\"wpforms[fields][157]\" aria-errormessage=\"wpforms-24968-field_157-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-25\" ><div id=\"wpforms-24968-field_158-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"158\"><div id=\"wpforms-24968-field_158\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_158-error\"><h5>2nd registration number (optional)<\/h5>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_159-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"159\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_159\" aria-hidden=\"false\">1 Vignette \/ 2nd registration number<\/label><input type=\"text\" id=\"wpforms-24968-field_159\" class=\"wpforms-field-medium\" name=\"wpforms[fields][159]\" aria-errormessage=\"wpforms-24968-field_159-error\" ><\/div><div id=\"wpforms-24968-field_160-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"160\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_160\" aria-hidden=\"false\">2 Vignette \/ 2nd registration number<\/label><input type=\"text\" id=\"wpforms-24968-field_160\" class=\"wpforms-field-medium\" name=\"wpforms[fields][160]\" aria-errormessage=\"wpforms-24968-field_160-error\" ><\/div><div id=\"wpforms-24968-field_161-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"161\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-24968-field_161\" aria-hidden=\"false\">3 Vignette \/ 3rd registration number<\/label><input type=\"text\" id=\"wpforms-24968-field_161\" class=\"wpforms-field-medium\" name=\"wpforms[fields][161]\" aria-errormessage=\"wpforms-24968-field_161-error\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-24968-field_176-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"176\"><div id=\"wpforms-24968-field_176\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_176-error\"><h4>Tax:<\/h4>\n<p>  The issue and renewal of the fourth vignette are subject to payment of a chancellery fee of \u20ac100 per year.<br \/>\n(01.01. - 31.12.)<br \/>\nIn the event of a new application during the calendar year, the fee due is calculated on a pro rata basis for the remaining quarters, with the quarter commencing on the date of application considered in its entirety for the purpose of calculating the fee.  <\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_179-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"179\"><div id=\"wpforms-24968-field_179\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_179-error\"><h4><\/h4>\n<table>\n<tbody>\n<tr>\n<td><strong>Date of request<\/strong><\/td>\n<td><strong>Fee to be paid:<\/strong><\/td>\n<\/tr>\n<tr>\n<td>January - March<\/td>\n<td>100\u20ac<\/td>\n<\/tr>\n<tr>\n<td>April - June<\/td>\n<td>75\u20ac<\/td>\n<\/tr>\n<tr>\n<td>July - September<\/td>\n<td>50\u20ac<\/td>\n<\/tr>\n<tr>\n<td>October - December<\/td>\n<td>25\u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>  Payable at the Biergerzenter or by bank transfer<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_178-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"178\"><div id=\"wpforms-24968-field_178\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_178-error\"><h4>Bank accounts:<\/h4>\n<p>  CCPLLULL LU43 1111 0085 0364 0000 CCRALULL LU21 0090 0000 3000 4634 BCEELULL LU86 0019 2801 0110 8000 BILLLULL LU29 0023 1530 8100 0000 BGLLULL LU21 0030 0343 0093 0000 Communication: sticker \/ registration number<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_53-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"53\"><div id=\"wpforms-24968-field_53\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-24968-field_53-error\"><h4><span style=\"color: #ff0000\">Important information:<\/span><\/h4>\n<p><span style=\"color: #ff0000\">1. The application must be accompanied by a copy of the vehicle registration certificate (Zulassungsbescheinigung).<\/span><\/p>\n<p><span style=\"color: #ff0000\">2. No registration number may appear on more than one sticker.<\/span><\/p>\n<p><span style=\"color: #ff0000\">3. The vignette is issued after payment of the fee.<\/span><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-24968-field_59-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"59\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_59\">A copy of the vehicle registration certificate(s) (Carte Grise, Zulassungsbescheinigung) \/ Rental\/leasing contract, if applicable, must be enclosed. <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div\n\t\tclass=\"wpforms-uploader wpforms-field-required\"\n\t\tdata-field-id=\"59\"\n\t\tdata-form-id=\"24968\"\n\t\tdata-input-name=\"wpforms_24968_59\"\n\t\tdata-extensions=\"pdf,doc,docx,png,jpg\"\n\t\tdata-max-size=\"67108864\"\n\t\tdata-max-file-number=\"5\"\n\t\tdata-post-max-size=\"67108864\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">You can upload up to 5 files.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-24968-field_59\"\n\t\tname=\"wpforms_24968_59\" required\t\tvalue=\"\">\n<\/div><div id=\"wpforms-24968-field_36-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"36\"><label class=\"wpforms-field-label\">RGPD Agreement   <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-24968-field_36\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-24968-field_36_1\" name=\"wpforms[fields][36][]\" value=\"I consent to this site storing my submitted information so that they may respond to my request.\" aria-errormessage=\"wpforms-24968-field_36_1-error\" aria-describedby=\"wpforms-24968-field_36-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-24968-field_36_1\">I consent to this site storing my submitted information so that they may respond to my request.<\/label><\/li><\/ul><div id=\"wpforms-24968-field_36-description\" class=\"wpforms-field-description\">The data collected in this form is necessary for the processing of your file by the services of the Communal Administration, and if necessary by its subcontractors.\nIt is processed fairly and transparently in accordance with the General Data Protection Regulation (RGPD), and kept for the duration necessary for this processing as well as the applicable legal archiving period.\nIf you have any questions about the processing of personal data, you can contact the Data Protection Officer (DPO) at dpo@mamer.lu .  <\/div><\/div><div id=\"wpforms-24968-field_177-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"177\"><label class=\"wpforms-field-label\" for=\"wpforms-24968-field_177\">sigi-field<\/label><input type=\"text\" id=\"wpforms-24968-field_177\" class=\"wpforms-field-medium\" name=\"wpforms[fields][177]\" aria-errormessage=\"wpforms-24968-field_177-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"24968\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-24968\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet ...\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --> <\/span><\/p>\n<p><\/p>\n<p>The certificate of residence is issued by the commune of residence.<br \/>The present is sent by post.<br \/>A certificate of residence can also be generated via <strong><a href=\"https:\/\/guichet.public.lu\/fr\/citoyens\/citoyennete\/certificat-casier-judiciaire\/certificat-copie\/certificat-residence.html#bloub-7\/\">MyGuichet.lu<\/a><\/strong><br \/>by logging on to your private area.<br \/>For further information, please contact the <strong><a href=\"https:\/\/mamer.lu\/en\/commune\/administration\/biergercenter-department\/\">Biergerzenter<\/a><\/strong><\/p>\n<p><strong><style id=\"wpforms-css-vars-20799\">\n\t\t\t\t#wpforms-20799 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20799\"><form id=\"wpforms-form-20799\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20799\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761\" data-token=\"f157c52937d7849a9277f3b745695033\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20799-field_32-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"32\"><div id=\"wpforms-20799-field_32\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20799-field_32-error\"><h6><strong>Certificat de R\u00e9sidence<\/strong><\/h6>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20799-field_30-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"30\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20799-field_30\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][30][first]\" aria-errormessage=\"wpforms-20799-field_30-error\" required><label for=\"wpforms-20799-field_30\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20799-field_30-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][30][last]\" aria-errormessage=\"wpforms-20799-field_30-last-error\" required><label for=\"wpforms-20799-field_30-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-20799-field_33-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"33\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_33\">Date de naissance <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-20799-field_33\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][33][date]\" aria-errormessage=\"wpforms-20799-field_33-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-20799-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_6\">Route et No:  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20799-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-20799-field_6-error\" required><\/div><div id=\"wpforms-20799-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_7\">Localit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20799-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-20799-field_7-error\" required><\/div><div id=\"wpforms-20799-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_8\">Code Postal <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20799-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-20799-field_8-error\" required><\/div><div id=\"wpforms-20799-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_5\">Telefon <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-20799-field_5\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-20799-field_5-error\" required><\/div><div id=\"wpforms-20799-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_3\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20799-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20799-field_3-error\" required><\/div><div id=\"wpforms-20799-field_25-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_25\">Ajouter la situation de famille <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-20799-field_25\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][25]\" required=\"required\"><option value=\"Non\"  class=\"choice-2 depth-1\"  >Non<\/option><option value=\"Oui\"  class=\"choice-1 depth-1\"  >Oui<\/option><\/select><\/div><div id=\"wpforms-20799-field_26-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_26\">Ajouter la nationalit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-20799-field_26\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][26]\" required=\"required\"><option value=\"Non\"  class=\"choice-2 depth-1\"  >Non<\/option><option value=\"Oui\"  class=\"choice-1 depth-1\"  >Oui<\/option><\/select><\/div><div id=\"wpforms-20799-field_24-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_24\">Ajouter le num\u00e9ro d&#039;identification <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-20799-field_24\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][24]\" required=\"required\"><option value=\"Non\"  class=\"choice-2 depth-1\"  >Non<\/option><option value=\"Oui \"  class=\"choice-1 depth-1\"  >Oui<\/option><\/select><\/div><div id=\"wpforms-20799-field_27-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"27\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_27\">Ajouter l&#039;histoire des adresses <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-20799-field_27\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][27]\" required=\"required\"><option value=\"Ne pas afficher l&#039;historique des adresses\"  class=\"choice-1 depth-1\"  >Ne pas afficher l'historique des adresses<\/option><option value=\"Adresse pr\u00e9c\u00e9dente\"  class=\"choice-3 depth-1\"  >Adresse pr\u00e9c\u00e9dente<\/option><option value=\"Toutes les adresses\"  class=\"choice-2 depth-1\"  >Toutes les adresses<\/option><\/select><\/div><div id=\"wpforms-20799-field_29-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"29\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_29\">No de copies<\/label><select id=\"wpforms-20799-field_29\" class=\"wpforms-field-medium\" name=\"wpforms[fields][29]\"><option value=\"1\"  class=\"choice-1 depth-1\"  >1<\/option><option value=\"2\"  class=\"choice-2 depth-1\"  >2<\/option><\/select><\/div><div id=\"wpforms-20799-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_16\">Remarques<\/label><input type=\"text\" id=\"wpforms-20799-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-20799-field_16-error\" ><\/div><div id=\"wpforms-20799-field_17-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"17\"><label class=\"wpforms-field-label\">Accord RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20799-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20799-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.\" aria-errormessage=\"wpforms-20799-field_17_1-error\" aria-describedby=\"wpforms-20799-field_17-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20799-field_17_1\">Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.<\/label><\/li><\/ul><div id=\"wpforms-20799-field_17-description\" class=\"wpforms-field-description\">Les donn\u00e9es r\u00e9colt\u00e9es dans ce formulaire sont n\u00e9cessaires au traitement de votre dossier par les services de l\u2019Administration communale, et le cas \u00e9ch\u00e9ant par ses sous-traitants. Elles sont trait\u00e9es de mani\u00e8re loyale et transparente conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD), et conserv\u00e9es la dur\u00e9e n\u00e9cessaire \u00e0 ce traitement ainsi qu\u2019au d\u00e9lai d\u2019archivage l\u00e9gal applicable.\r\n\r\nEn cas de question au sujet du traitement des donn\u00e9es personnelles, vous pouvez contacter le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPD) \u00e0 l\u2019adresse dpo@mamer.lu .<\/div><\/div><div id=\"wpforms-20799-field_18-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-20799-field_18\">sigi-field<\/label><input type=\"text\" id=\"wpforms-20799-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" aria-errormessage=\"wpforms-20799-field_18-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20799\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20799\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/strong><\/p>\n<p><\/p>\n<p>The extended certificate of residence is issued by the commune of residence and includes your personal details, those of your spouse\/partner and children living at the same address.<br \/>The present will be sent to you by post.<br \/>You can also generate an extended certificate of residence via <strong><a href=\"https:\/\/guichet.public.lu\/fr\/citoyens\/citoyennete\/certificat-casier-judiciaire\/certificat-copie\/certificat-residence.html#bloub-7\/\">MyGuichet.lu<\/a><\/strong><br \/>by logging on to your private area.<br \/>For further information, please contact the <strong><a href=\"https:\/\/mamer.lu\/en\/commune\/administration\/biergercenter-department\/\">Biergerzenter<\/a><\/strong><\/p>\n<p><strong><style id=\"wpforms-css-vars-20822\">\n\t\t\t\t#wpforms-20822 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20822\"><form id=\"wpforms-form-20822\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20822\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761\" data-token=\"73d93993959a856af6864c54da20cb92\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20822-field_26-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"26\"><div id=\"wpforms-20822-field_26\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20822-field_26-error\"><h6><strong>Certificat de R\u00e9sidence \u00e9largi<\/strong><\/h6>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20822-field_25-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"25\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20822-field_25\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][25][first]\" aria-errormessage=\"wpforms-20822-field_25-error\" required><label for=\"wpforms-20822-field_25\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20822-field_25-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][25][last]\" aria-errormessage=\"wpforms-20822-field_25-last-error\" required><label for=\"wpforms-20822-field_25-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-20822-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_1\">Date de naissance <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20822-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-20822-field_1-error\" required><\/div><div id=\"wpforms-20822-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_6\">Route et No:  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20822-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-20822-field_6-error\" required><\/div><div id=\"wpforms-20822-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_7\">Localit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20822-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-20822-field_7-error\" required><\/div><div id=\"wpforms-20822-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_8\">Code Postal <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20822-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-20822-field_8-error\" required><\/div><div id=\"wpforms-20822-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_5\">Telefon <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-20822-field_5\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-20822-field_5-error\" required><\/div><div id=\"wpforms-20822-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_3\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20822-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20822-field_3-error\" required><\/div><div id=\"wpforms-20822-field_23-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_23\">Ajouter la nationalit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-20822-field_23\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][23]\" required=\"required\"><option value=\"Non\"  class=\"choice-2 depth-1\"  >Non<\/option><option value=\"Oui\"  class=\"choice-1 depth-1\"  >Oui<\/option><\/select><\/div><div id=\"wpforms-20822-field_22-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_22\">Ajouter le num\u00e9ro d&#039;identification <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-20822-field_22\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][22]\" required=\"required\"><option value=\"Non\"  class=\"choice-2 depth-1\"  >Non<\/option><option value=\"Oui\"  class=\"choice-1 depth-1\"  >Oui<\/option><\/select><\/div><div id=\"wpforms-20822-field_24-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_24\">No de copies<\/label><select id=\"wpforms-20822-field_24\" class=\"wpforms-field-medium\" name=\"wpforms[fields][24]\"><option value=\"1\"  class=\"choice-1 depth-1\"  >1<\/option><option value=\"2\"  class=\"choice-2 depth-1\"  >2<\/option><\/select><\/div><div id=\"wpforms-20822-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_16\">Remarques<\/label><input type=\"text\" id=\"wpforms-20822-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-20822-field_16-error\" ><\/div><div id=\"wpforms-20822-field_17-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"17\"><label class=\"wpforms-field-label\">Accord RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20822-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20822-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.\" aria-errormessage=\"wpforms-20822-field_17_1-error\" aria-describedby=\"wpforms-20822-field_17-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20822-field_17_1\">Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.<\/label><\/li><\/ul><div id=\"wpforms-20822-field_17-description\" class=\"wpforms-field-description\">Les donn\u00e9es r\u00e9colt\u00e9es dans ce formulaire sont n\u00e9cessaires au traitement de votre dossier par les services de l\u2019Administration communale, et le cas \u00e9ch\u00e9ant par ses sous-traitants. Elles sont trait\u00e9es de mani\u00e8re loyale et transparente conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD), et conserv\u00e9es la dur\u00e9e n\u00e9cessaire \u00e0 ce traitement ainsi qu\u2019au d\u00e9lai d\u2019archivage l\u00e9gal applicable.\r\n\r\nEn cas de question au sujet du traitement des donn\u00e9es personnelles, vous pouvez contacter le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPD) \u00e0 l\u2019adresse dpo@mamer.lu .<\/div><\/div><div id=\"wpforms-20822-field_18-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-20822-field_18\">sigi-field<\/label><input type=\"text\" id=\"wpforms-20822-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" aria-errormessage=\"wpforms-20822-field_18-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20822\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20822\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/strong><\/p>\n<p><\/p>\n<p>The certificate of residence is issued by the commune of residence.<br \/>The present is sent by post.<br \/>A certificate of residence can also be generated via <strong><a href=\"https:\/\/guichet.public.lu\/fr\/citoyens\/citoyennete\/certificat-casier-judiciaire\/certificat-copie\/certificat-residence.html#bloub-7\/\">MyGuichet.lu<\/a><\/strong><br \/>by logging on to your private area.<br \/>For further information, please contact the <strong><a href=\"https:\/\/mamer.lu\/en\/commune\/administration\/biergercenter-department\/\">Biergerzenter<\/a><\/strong><\/p>\n<style id=\"wpforms-css-vars-20827\">\n\t\t\t\t#wpforms-20827 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20827\"><form id=\"wpforms-form-20827\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20827\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761\" data-token=\"954beaf34a73f07e037cf6f9e5901771\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20827-field_23-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"23\"><div id=\"wpforms-20827-field_23\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20827-field_23-error\"><h6><strong>demande d'inscription aux listes \u00e9lectorales<\/strong><\/h6>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20827-field_19-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"19\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20827-field_19\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][19][first]\" aria-errormessage=\"wpforms-20827-field_19-error\" required><label for=\"wpforms-20827-field_19\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20827-field_19-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][19][last]\" aria-errormessage=\"wpforms-20827-field_19-last-error\" required><label for=\"wpforms-20827-field_19-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-20827-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_1\">Date de naissance <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20827-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-20827-field_1-error\" required><\/div><div id=\"wpforms-20827-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_6\">Route et No:  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20827-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-20827-field_6-error\" required><\/div><div id=\"wpforms-20827-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_7\">Localit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20827-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-20827-field_7-error\" required><\/div><div id=\"wpforms-20827-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_8\">Code Postal <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20827-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-20827-field_8-error\" required><\/div><div id=\"wpforms-20827-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_5\">Telefon <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-20827-field_5\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-20827-field_5-error\" required><\/div><div id=\"wpforms-20827-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_3\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20827-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20827-field_3-error\" required><\/div><div id=\"wpforms-20827-field_21-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_21\">No de copies<\/label><select id=\"wpforms-20827-field_21\" class=\"wpforms-field-medium\" name=\"wpforms[fields][21]\"><option value=\"1\"  class=\"choice-1 depth-1\"  >1<\/option><option value=\"2\"  class=\"choice-2 depth-1\"  >2<\/option><\/select><\/div><div id=\"wpforms-20827-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_16\">Remarques<\/label><input type=\"text\" id=\"wpforms-20827-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-20827-field_16-error\" ><\/div><div id=\"wpforms-20827-field_17-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"17\"><label class=\"wpforms-field-label\">Accord RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20827-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20827-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.\" aria-errormessage=\"wpforms-20827-field_17_1-error\" aria-describedby=\"wpforms-20827-field_17-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20827-field_17_1\">Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.<\/label><\/li><\/ul><div id=\"wpforms-20827-field_17-description\" class=\"wpforms-field-description\">Les donn\u00e9es r\u00e9colt\u00e9es dans ce formulaire sont n\u00e9cessaires au traitement de votre dossier par les services de l\u2019Administration communale, et le cas \u00e9ch\u00e9ant par ses sous-traitants. Elles sont trait\u00e9es de mani\u00e8re loyale et transparente conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD), et conserv\u00e9es la dur\u00e9e n\u00e9cessaire \u00e0 ce traitement ainsi qu\u2019au d\u00e9lai d\u2019archivage l\u00e9gal applicable.\r\n\r\nEn cas de question au sujet du traitement des donn\u00e9es personnelles, vous pouvez contacter le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPD) \u00e0 l\u2019adresse dpo@mamer.lu .<\/div><\/div><div id=\"wpforms-20827-field_18-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-20827-field_18\">sigi-field<\/label><input type=\"text\" id=\"wpforms-20827-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" aria-errormessage=\"wpforms-20827-field_18-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20827\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20827\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<p><\/p>\n<p>The requested death certificate will be sent to you by post to the address indicated.<br \/>For further information, please contact <a href=\"https:\/\/mamer.lu\/en\/commune\/administration\/biergercenter-department\/\"><strong>Biergerzenter<\/strong><\/a><\/p>\n<p><strong><style id=\"wpforms-css-vars-20833\">\n\t\t\t\t#wpforms-20833 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20833\"><form id=\"wpforms-form-20833\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20833\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761\" data-token=\"3c17f9e03322266921204009a0d9ac12\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20833-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"2\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20833-field_2\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][2][first]\" aria-errormessage=\"wpforms-20833-field_2-error\" required><label for=\"wpforms-20833-field_2\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20833-field_2-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][2][last]\" aria-errormessage=\"wpforms-20833-field_2-last-error\" required><label for=\"wpforms-20833-field_2-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-20833-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_1\">Date de naissance<\/label><input type=\"text\" id=\"wpforms-20833-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-20833-field_1-error\" ><\/div><div id=\"wpforms-20833-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_6\">Route et No:  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20833-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-20833-field_6-error\" required><\/div><div id=\"wpforms-20833-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_7\">Localit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20833-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-20833-field_7-error\" required><\/div><div id=\"wpforms-20833-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_8\">Code Postal <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20833-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-20833-field_8-error\" required><\/div><div id=\"wpforms-20833-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_5\">Telefon <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-20833-field_5\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-20833-field_5-error\" required><\/div><div id=\"wpforms-20833-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_3\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20833-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20833-field_3-error\" required><\/div><div id=\"wpforms-20833-field_26-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"26\"><fieldset><legend class=\"wpforms-field-label\">Nom du d\u00e9funt <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20833-field_26\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][26][first]\" aria-errormessage=\"wpforms-20833-field_26-error\" required><label for=\"wpforms-20833-field_26\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20833-field_26-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][26][last]\" aria-errormessage=\"wpforms-20833-field_26-last-error\" required><label for=\"wpforms-20833-field_26-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-20833-field_25-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_25\">Date du d\u00e9c\u00e8s<\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-20833-field_25\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][25][date]\" aria-errormessage=\"wpforms-20833-field_25-error\" ><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-20833-field_23-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_23\">Lieu du d\u00e9c\u00e8s<\/label><select id=\"wpforms-20833-field_23\" class=\"wpforms-field-medium\" name=\"wpforms[fields][23]\"><option value=\"Mamer\"  class=\"choice-1 depth-1\"  >Mamer<\/option><option value=\"Capellen\"  class=\"choice-2 depth-1\"  >Capellen<\/option><option value=\"Holzem\"  class=\"choice-3 depth-1\"  >Holzem<\/option><\/select><\/div><div id=\"wpforms-20833-field_24-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_24\">No de copies<\/label><select id=\"wpforms-20833-field_24\" class=\"wpforms-field-medium\" name=\"wpforms[fields][24]\"><option value=\"1\"  class=\"choice-1 depth-1\"  >1<\/option><option value=\"2\"  class=\"choice-2 depth-1\"  >2<\/option><\/select><\/div><div id=\"wpforms-20833-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_16\">Remarques<\/label><input type=\"text\" id=\"wpforms-20833-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-20833-field_16-error\" ><\/div><div id=\"wpforms-20833-field_17-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"17\"><label class=\"wpforms-field-label\">Accord RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20833-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20833-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.\" aria-errormessage=\"wpforms-20833-field_17_1-error\" aria-describedby=\"wpforms-20833-field_17-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20833-field_17_1\">Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.<\/label><\/li><\/ul><div id=\"wpforms-20833-field_17-description\" class=\"wpforms-field-description\">Les donn\u00e9es r\u00e9colt\u00e9es dans ce formulaire sont n\u00e9cessaires au traitement de votre dossier par les services de l\u2019Administration communale, et le cas \u00e9ch\u00e9ant par ses sous-traitants. Elles sont trait\u00e9es de mani\u00e8re loyale et transparente conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD), et conserv\u00e9es la dur\u00e9e n\u00e9cessaire \u00e0 ce traitement ainsi qu\u2019au d\u00e9lai d\u2019archivage l\u00e9gal applicable.\r\n\r\nEn cas de question au sujet du traitement des donn\u00e9es personnelles, vous pouvez contacter le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPD) \u00e0 l\u2019adresse dpo@mamer.lu .<\/div><\/div><div id=\"wpforms-20833-field_18-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-20833-field_18\">sigi-field<\/label><input type=\"text\" id=\"wpforms-20833-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" aria-errormessage=\"wpforms-20833-field_18-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20833\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20833\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/strong><\/p>\n<p><\/p>\n<p>The requested marriage certificate will be sent by post to the address indicated.<br \/>For further information, please contact <strong><a href=\"https:\/\/mamer.lu\/en\/commune\/administration\/biergercenter-department\/\">Biergerzenter<\/a><\/strong><\/p>\n<p><strong><style id=\"wpforms-css-vars-20842\">\n\t\t\t\t#wpforms-20842 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20842\"><form id=\"wpforms-form-20842\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20842\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761\" data-token=\"6bb88e32f8a553ce1ba1dd75f5c8c87a\" data-token-time=\"1788392575\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20842-field_22-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"22\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20842-field_22\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][22][first]\" aria-errormessage=\"wpforms-20842-field_22-error\" required><label for=\"wpforms-20842-field_22\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20842-field_22-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][22][last]\" aria-errormessage=\"wpforms-20842-field_22-last-error\" required><label for=\"wpforms-20842-field_22-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-20842-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_1\">Date de naissance <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20842-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-20842-field_1-error\" required><\/div><div id=\"wpforms-20842-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_6\">Route et No:  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20842-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-20842-field_6-error\" required><\/div><div id=\"wpforms-20842-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_7\">Localit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20842-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-20842-field_7-error\" required><\/div><div id=\"wpforms-20842-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_8\">Code Postal <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20842-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-20842-field_8-error\" required><\/div><div id=\"wpforms-20842-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_5\">Telefon <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-20842-field_5\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-20842-field_5-error\" required><\/div><div id=\"wpforms-20842-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_3\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20842-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20842-field_3-error\" required><\/div><div id=\"wpforms-20842-field_26-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_26\">Date de mariage <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-20842-field_26\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][26][date]\" aria-errormessage=\"wpforms-20842-field_26-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-20842-field_24-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_24\">Lieu du mariage <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-20842-field_24\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][24]\" required=\"required\"><option value=\"Mamer\"  class=\"choice-1 depth-1\"  >Mamer<\/option><\/select><\/div><div id=\"wpforms-20842-field_25-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_25\">No de copies <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-20842-field_25\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][25]\" required=\"required\"><option value=\"1\"  class=\"choice-1 depth-1\"  >1<\/option><option value=\"2\"  class=\"choice-2 depth-1\"  >2<\/option><\/select><\/div><div id=\"wpforms-20842-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_16\">Remarques<\/label><input type=\"text\" id=\"wpforms-20842-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-20842-field_16-error\" ><\/div><div id=\"wpforms-20842-field_17-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"17\"><label class=\"wpforms-field-label\">Accord RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20842-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20842-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.\" aria-errormessage=\"wpforms-20842-field_17_1-error\" aria-describedby=\"wpforms-20842-field_17-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20842-field_17_1\">Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.<\/label><\/li><\/ul><div id=\"wpforms-20842-field_17-description\" class=\"wpforms-field-description\">Les donn\u00e9es r\u00e9colt\u00e9es dans ce formulaire sont n\u00e9cessaires au traitement de votre dossier par les services de l\u2019Administration communale, et le cas \u00e9ch\u00e9ant par ses sous-traitants. Elles sont trait\u00e9es de mani\u00e8re loyale et transparente conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD), et conserv\u00e9es la dur\u00e9e n\u00e9cessaire \u00e0 ce traitement ainsi qu\u2019au d\u00e9lai d\u2019archivage l\u00e9gal applicable.\r\n\r\nEn cas de question au sujet du traitement des donn\u00e9es personnelles, vous pouvez contacter le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPD) \u00e0 l\u2019adresse dpo@mamer.lu .<\/div><\/div><div id=\"wpforms-20842-field_18-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-20842-field_18\">sigi-field<\/label><input type=\"text\" id=\"wpforms-20842-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" aria-errormessage=\"wpforms-20842-field_18-error\" ><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20842\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20842\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --> <\/strong><\/p>\n<p><\/p>\n<p><strong><style id=\"wpforms-css-vars-20847\">\n\t\t\t\t#wpforms-20847 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20847\"><form id=\"wpforms-form-20847\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20847\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761\" data-token=\"cd999ef37d84b6e223a3de7204755a81\" data-token-time=\"1788392576\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20847-field_24-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"24\"><fieldset><legend class=\"wpforms-field-label\">Nom et Pr\u00e9nom de l&#039;\u00e9l\u00e8ve <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-20847-field_24\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][24][first]\" aria-errormessage=\"wpforms-20847-field_24-error\" required><label for=\"wpforms-20847-field_24\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-20847-field_24-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][24][last]\" aria-errormessage=\"wpforms-20847-field_24-last-error\" required><label for=\"wpforms-20847-field_24-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-20847-field_28-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_28\">Date de naissance<\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-20847-field_28\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][28][date]\" aria-errormessage=\"wpforms-20847-field_28-error\" ><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-20847-field_30-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"30\"><div id=\"wpforms-20847-field_30\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-20847-field_30-error\"><h4>Adresse actuelle:<\/h4>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-20847-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_6\">Route et No:  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20847-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-20847-field_6-error\" required><\/div><div id=\"wpforms-20847-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_7\">Localit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20847-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-20847-field_7-error\" required><\/div><div id=\"wpforms-20847-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_8\">Code Postal <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20847-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-20847-field_8-error\" required><\/div><div id=\"wpforms-20847-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_5\">Telefon <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-20847-field_5\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-20847-field_5-error\" required><\/div><div id=\"wpforms-20847-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_3\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20847-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20847-field_3-error\" required><\/div><div id=\"wpforms-20847-field_26-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_26\">Type de certificat<\/label><select id=\"wpforms-20847-field_26\" class=\"wpforms-field-medium\" name=\"wpforms[fields][26]\"><option value=\"Ann\u00e9e en cours\"  class=\"choice-1 depth-1\"  >Ann\u00e9e en cours<\/option><option value=\"Historique des ann\u00e9es scolaires\"  class=\"choice-2 depth-1\"  >Historique des ann\u00e9es scolaires<\/option><\/select><\/div><div id=\"wpforms-20847-field_22-container\" class=\"wpforms-field wpforms-field-richtext wpforms-field-medium\" data-field-type=\"richtext\" data-field-id=\"22\"><fieldset><legend class=\"wpforms-field-label\">D\u00e9signation de\/des \u00e9cole(s) fr\u00e9quent\u00e9e(s) <\/legend><div id=\"wp-wpforms-20847-field_22-wrap\" class=\"wp-core-ui wp-editor-wrap tmce-active\"><link rel='stylesheet' id='dashicons-css' href='https:\/\/mamer.lu\/wp-includes\/css\/dashicons.min.css' media='all' \/>\n<link rel='stylesheet' id='editor-buttons-css' href='https:\/\/mamer.lu\/wp-includes\/css\/editor.min.css' media='all' \/>\n<div id=\"wp-wpforms-20847-field_22-editor-tools\" class=\"wp-editor-tools hide-if-no-js\"><div class=\"wp-editor-tabs\"><button type=\"button\" id=\"wpforms-20847-field_22-tmce\" aria-pressed=\"true\" class=\"wp-switch-editor switch-tmce\" data-wp-editor-id=\"wpforms-20847-field_22\">Visual<\/button>\n<button type=\"button\" id=\"wpforms-20847-field_22-html\" class=\"wp-switch-editor switch-html\" data-wp-editor-id=\"wpforms-20847-field_22\">Code<\/button>\n<\/div>\n<\/div>\n<div id=\"wp-wpforms-20847-field_22-editor-container\" class=\"wp-editor-container\"><div id=\"qt_wpforms-20847-field_22_toolbar\" class=\"quicktags-toolbar hide-if-no-js\"><\/div><textarea class=\"wp-editor-area\" style=\"height: 120px\" autocomplete=\"off\" cols=\"40\" name=\"wpforms[fields][22]\" id=\"wpforms-20847-field_22\"><\/textarea><\/div>\n<\/div>\n\n<\/fieldset><\/div><div id=\"wpforms-20847-field_23-container\" class=\"wpforms-field wpforms-field-richtext wpforms-field-medium\" data-field-type=\"richtext\" data-field-id=\"23\"><fieldset><legend class=\"wpforms-field-label\">Nom des Enseignants<\/legend><div id=\"wp-wpforms-20847-field_23-wrap\" class=\"wp-core-ui wp-editor-wrap tmce-active\"><div id=\"wp-wpforms-20847-field_23-editor-tools\" class=\"wp-editor-tools hide-if-no-js\"><div class=\"wp-editor-tabs\"><button type=\"button\" id=\"wpforms-20847-field_23-tmce\" aria-pressed=\"true\" class=\"wp-switch-editor switch-tmce\" data-wp-editor-id=\"wpforms-20847-field_23\">Visual<\/button>\n<button type=\"button\" id=\"wpforms-20847-field_23-html\" class=\"wp-switch-editor switch-html\" data-wp-editor-id=\"wpforms-20847-field_23\">Code<\/button>\n<\/div>\n<\/div>\n<div id=\"wp-wpforms-20847-field_23-editor-container\" class=\"wp-editor-container\"><div id=\"qt_wpforms-20847-field_23_toolbar\" class=\"quicktags-toolbar hide-if-no-js\"><\/div><textarea class=\"wp-editor-area\" style=\"height: 120px\" autocomplete=\"off\" cols=\"40\" name=\"wpforms[fields][23]\" id=\"wpforms-20847-field_23\"><\/textarea><\/div>\n<\/div>\n\n<\/fieldset><\/div><div id=\"wpforms-20847-field_27-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"27\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_27\">No de copies<\/label><select id=\"wpforms-20847-field_27\" class=\"wpforms-field-medium\" name=\"wpforms[fields][27]\"><option value=\"1\"  class=\"choice-1 depth-1\"  >1<\/option><option value=\"2\"  class=\"choice-2 depth-1\"  >2<\/option><\/select><\/div><div id=\"wpforms-20847-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_16\">Remarques<\/label><input type=\"text\" id=\"wpforms-20847-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-20847-field_16-error\" ><\/div><div id=\"wpforms-20847-field_17-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"17\"><label class=\"wpforms-field-label\">Accord RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20847-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20847-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.\" aria-errormessage=\"wpforms-20847-field_17_1-error\" aria-describedby=\"wpforms-20847-field_17-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20847-field_17_1\">Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.<\/label><\/li><\/ul><div id=\"wpforms-20847-field_17-description\" class=\"wpforms-field-description\">Les donn\u00e9es r\u00e9colt\u00e9es dans ce formulaire sont n\u00e9cessaires au traitement de votre dossier par les services de l\u2019Administration communale, et le cas \u00e9ch\u00e9ant par ses sous-traitants. Elles sont trait\u00e9es de mani\u00e8re loyale et transparente conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD), et conserv\u00e9es la dur\u00e9e n\u00e9cessaire \u00e0 ce traitement ainsi qu\u2019au d\u00e9lai d\u2019archivage l\u00e9gal applicable.\n\nEn cas de question au sujet du traitement des donn\u00e9es personnelles, vous pouvez contacter le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPD) \u00e0 l\u2019adresse dpo@mamer.lu .<\/div><\/div><div id=\"wpforms-20847-field_18-container\" class=\"wpforms-field wpforms-field-text sigi-field\" data-field-type=\"text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_18\">sigi-field<\/label><input type=\"text\" id=\"wpforms-20847-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" aria-errormessage=\"wpforms-20847-field_18-error\" ><\/div><div id=\"wpforms-20847-field_31-container\" class=\"wpforms-field wpforms-field-captcha\" data-field-type=\"captcha\" data-field-id=\"31\"><label class=\"wpforms-field-label\" for=\"wpforms-20847-field_31\">CAPTCHA personnalis\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label>\t\t\t<div class=\"wpforms-captcha-math\">\n\t\t\t\t<span id=\"wpforms-20847-field_31-question\" class=\"wpforms-captcha-equation\">\n\t\t\t\t\t<span class=\"n1\">6<\/span>\n\t\t\t\t\t\t\t<span class=\"cal\">*<\/span>\n\t\t\t\t\t\t\t<span class=\"n2\">5<\/span>\t\t\t\t\t<span class=\"e\">=<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<input type=\"text\" id=\"wpforms-20847-field_31\" class=\"wpforms-field-medium wpforms-field-required a\" data-rule-wpf-captcha=\"math\" data-is-wrapped-field=\"1\" name=\"wpforms[fields][31][a]\" aria-errormessage=\"wpforms-20847-field_31-error\" aria-describedby=\"wpforms-20847-field_31-question\" required>\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][31][cal]\" class=\"cal\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][31][n2]\" class=\"n2\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][31][n1]\" class=\"n1\">\n\t\t\t<\/div>\n\t\t\t<\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20847\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20847\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/strong><\/p>\n<p><\/p>\n<p>The requested death certificate will be sent to you by post to the address indicated.<br \/>For further information, please contact <a href=\"https:\/\/mamer.lu\/en\/commune\/administration\/biergercenter-department\/\"><strong>Biergerzenter<\/strong><\/a><\/p>\n<p><strong><style id=\"wpforms-css-vars-49834\">\n\t\t\t\t#wpforms-49834 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-49834\"><form id=\"wpforms-form-49834\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"49834\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/27761?wpforms_form_id=49834\" data-token=\"efdfcb391be97b8e5d856a2bef2ab478\" data-token-time=\"1788392576\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-49834-field_169-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"169\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-49834-field_170-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"170\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_170\">Pr\u00e9nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-49834-field_170\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][170]\" aria-errormessage=\"wpforms-49834-field_170-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-49834-field_171-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"171\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_171\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-49834-field_171\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][171]\" aria-errormessage=\"wpforms-49834-field_171-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-49834-field_163-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"163\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-49834-field_164-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"164\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_164\">N\u00b0 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-49834-field_164\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][164]\" aria-errormessage=\"wpforms-49834-field_164-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-49834-field_177-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"177\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_177\">Rue <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-49834-field_177\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][177]\" aria-errormessage=\"wpforms-49834-field_177-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-49834-field_166-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"166\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-49834-field_167-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"167\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_167\">Code Postal <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-49834-field_167\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][167]\" aria-errormessage=\"wpforms-49834-field_167-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-49834-field_168-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"168\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_168\">Localit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-49834-field_168\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][168]\" required=\"required\"><option value=\"Mamer\"  class=\"choice-1 depth-1\"  >Mamer<\/option><option value=\"Capellen\"  class=\"choice-2 depth-1\"  >Capellen<\/option><option value=\"Holzem\"  class=\"choice-3 depth-1\"  >Holzem<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-49834-field_172-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"172\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-67\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-49834-field_175-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"175\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_175\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-49834-field_175\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][175]\" aria-errormessage=\"wpforms-49834-field_175-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-67\" ><div id=\"wpforms-49834-field_174-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"174\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_174\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-49834-field_174\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][174]\" spellcheck=\"false\" aria-errormessage=\"wpforms-49834-field_174-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-49834-field_52-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"52\"><div id=\"wpforms-49834-field_52\" class=\"wpforms-field-large wpforms-field-row\" aria-errormessage=\"wpforms-49834-field_52-error\"><h5><span style=\"color: #000000\">Important :<\/span><\/h5>\n<p><span style=\"color: #000000\">1. Il est obligatoire de joindre le certificat v\u00e9t\u00e9rinaire. <a rel=\"noopener\" target=\"_blank\" href=\"https:\/\/guichet.public.lu\/dam-assets\/catalogue-formulaires\/famille-education\/document\/animaux-domestiques\/certificat-veterinaire\/certificat-veterinaire.pdf\">(voir mod\u00e8le)<\/a><br \/>\n<\/span><\/p>\n<p><span style=\"color: #000000\">2. Il est obligatoire de joindre une pi\u00e8ce qui atteste qu\u2019un contrat d\u2019assurance responsabilit\u00e9 civile&nbsp;a \u00e9t\u00e9 conclu avec une soci\u00e9t\u00e9 agr\u00e9\u00e9e ou autoris\u00e9e \u00e0 op\u00e9rer au Luxembourg<\/span><\/p>\n<p><span style=\"color: #000000\">3. Pour la d\u00e9claration d'un chien suceptible d'\u00eatre dangereux, veuillez contacter directement le service Biergerzenter de l'administration communale<\/span><\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-49834-field_59-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"59\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_59\">Certificat v\u00e9t\u00e9rinaire <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div\n\t\tclass=\"wpforms-uploader wpforms-field-required\"\n\t\tdata-field-id=\"59\"\n\t\tdata-form-id=\"49834\"\n\t\tdata-input-name=\"wpforms_49834_59\"\n\t\tdata-extensions=\"pdf,doc,docx,png,jpg\"\n\t\tdata-max-size=\"67108864\"\n\t\tdata-max-file-number=\"5\"\n\t\tdata-post-max-size=\"67108864\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">You can upload up to 5 files.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-49834-field_59\"\n\t\tname=\"wpforms_49834_59\" required\t\tvalue=\"\">\n<\/div><div id=\"wpforms-49834-field_178-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"178\"><label class=\"wpforms-field-label\" for=\"wpforms-49834-field_178\">Document assurance <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div\n\t\tclass=\"wpforms-uploader wpforms-field-required\"\n\t\tdata-field-id=\"178\"\n\t\tdata-form-id=\"49834\"\n\t\tdata-input-name=\"wpforms_49834_178\"\n\t\tdata-extensions=\"pdf,doc,docx,png,jpg\"\n\t\tdata-max-size=\"67108864\"\n\t\tdata-max-file-number=\"5\"\n\t\tdata-post-max-size=\"67108864\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">You can upload up to 5 files.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-49834-field_178\"\n\t\tname=\"wpforms_49834_178\" required\t\tvalue=\"\">\n<\/div><div id=\"wpforms-49834-field_36-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"36\"><label class=\"wpforms-field-label\">Accord RGPD  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-49834-field_36\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-49834-field_36_1\" name=\"wpforms[fields][36][]\" value=\"Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.\" aria-errormessage=\"wpforms-49834-field_36_1-error\" aria-describedby=\"wpforms-49834-field_36-description\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-49834-field_36_1\">Je consens \u00e0 ce que ce site stocke mes informations envoy\u00e9es afin qu\u2019ils puissent r\u00e9pondre \u00e0 ma requ\u00eate.<\/label><\/li><\/ul><div id=\"wpforms-49834-field_36-description\" class=\"wpforms-field-description\">Les donn\u00e9es r\u00e9colt\u00e9es dans ce formulaire sont n\u00e9cessaires au traitement de votre dossier par les services de l\u2019Administration communale, et le cas \u00e9ch\u00e9ant par ses sous-traitants. Elles sont trait\u00e9es de mani\u00e8re loyale et transparente conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD), et conserv\u00e9es la dur\u00e9e n\u00e9cessaire \u00e0 ce traitement ainsi qu\u2019au d\u00e9lai d\u2019archivage l\u00e9gal applicable. En cas de question au sujet du traitement des donn\u00e9es personnelles, vous pouvez contacter le d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (DPD) \u00e0 l\u2019adresse dpo@mamer.lu .<\/div><\/div><\/div><!-- .wpforms-field-container --><input type=\"text\" name=\"7Rcqq\" value=\"\" style=\"display: none !important;\" \/><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"49834\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-49834\" class=\"wpforms-submit\" data-alt-text=\"En cours d&#039;envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mamer.lu\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --> <\/strong><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Night Card, Access card to the \u201cBike-Washsalon\u201d station, \u2026<\/p>\n","protected":false},"author":19,"featured_media":0,"parent":28200,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"class_list":["post-27761","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online requests - Mamer<\/title>\n<meta name=\"description\" content=\"%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mamer.lu\/en\/procedures-2\/applications\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online requests - Mamer\" \/>\n<meta property=\"og:description\" content=\"%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mamer.lu\/en\/procedures-2\/applications\/\" \/>\n<meta property=\"og:site_name\" content=\"Mamer\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T13:58:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mamer.lu\\\/en\\\/procedures-2\\\/applications\\\/\",\"url\":\"https:\\\/\\\/mamer.lu\\\/en\\\/procedures-2\\\/applications\\\/\",\"name\":\"Online requests - Mamer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mamer.lu\\\/#website\"},\"datePublished\":\"2024-06-19T15:36:06+00:00\",\"dateModified\":\"2026-08-03T13:58:01+00:00\",\"description\":\"%\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mamer.lu\\\/en\\\/procedures-2\\\/applications\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mamer.lu\\\/en\\\/procedures-2\\\/applications\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mamer.lu\\\/en\\\/procedures-2\\\/applications\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mamer.lu\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Citizen Service Desk\",\"item\":\"https:\\\/\\\/mamer.lu\\\/en\\\/procedures-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Online requests\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mamer.lu\\\/#website\",\"url\":\"https:\\\/\\\/mamer.lu\\\/\",\"name\":\"Mamer\",\"description\":\"Site web de la commune Mamer\",\"publisher\":{\"@id\":\"https:\\\/\\\/mamer.lu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mamer.lu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mamer.lu\\\/#organization\",\"name\":\"Mamer\",\"url\":\"https:\\\/\\\/mamer.lu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mamer.lu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Mamer\"},\"image\":{\"@id\":\"https:\\\/\\\/mamer.lu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online requests - Mamer","description":"%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mamer.lu\/en\/procedures-2\/applications\/","og_locale":"en_US","og_type":"article","og_title":"Online requests - Mamer","og_description":"%","og_url":"https:\/\/mamer.lu\/en\/procedures-2\/applications\/","og_site_name":"Mamer","article_modified_time":"2026-08-03T13:58:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mamer.lu\/en\/procedures-2\/applications\/","url":"https:\/\/mamer.lu\/en\/procedures-2\/applications\/","name":"Online requests - Mamer","isPartOf":{"@id":"https:\/\/mamer.lu\/#website"},"datePublished":"2024-06-19T15:36:06+00:00","dateModified":"2026-08-03T13:58:01+00:00","description":"%","breadcrumb":{"@id":"https:\/\/mamer.lu\/en\/procedures-2\/applications\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mamer.lu\/en\/procedures-2\/applications\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mamer.lu\/en\/procedures-2\/applications\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mamer.lu\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Citizen Service Desk","item":"https:\/\/mamer.lu\/en\/procedures-2\/"},{"@type":"ListItem","position":3,"name":"Online requests"}]},{"@type":"WebSite","@id":"https:\/\/mamer.lu\/#website","url":"https:\/\/mamer.lu\/","name":"Mamer","description":"Site web de la commune Mamer","publisher":{"@id":"https:\/\/mamer.lu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mamer.lu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mamer.lu\/#organization","name":"Mamer","url":"https:\/\/mamer.lu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mamer.lu\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Mamer"},"image":{"@id":"https:\/\/mamer.lu\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-10 01:42:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/comments?post=27761"}],"version-history":[{"count":16,"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\/revisions"}],"predecessor-version":[{"id":53819,"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/27761\/revisions\/53819"}],"up":[{"embeddable":true,"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/pages\/28200"}],"wp:attachment":[{"href":"https:\/\/mamer.lu\/en\/wp-json\/wp\/v2\/media?parent=27761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}